{"id":29213,"date":"2023-08-13T14:19:13","date_gmt":"2023-08-13T14:19:13","guid":{"rendered":"https:\/\/www.atomkraft-jatak.dk\/newsite\/?post_type=docs&#038;p=29213"},"modified":"2024-09-14T20:41:02","modified_gmt":"2024-09-14T20:41:02","password":"","slug":"purex-genbehandlingsmetode","status":"publish","type":"docs","link":"https:\/\/www.atomkraft-jatak.dk\/newsite\/dokumenter\/purex-genbehandlingsmetode\/","title":{"rendered":"PUREX &#8211; genbehandlingsmetoden"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\"><strong>Indledning<\/strong><\/h3>\n\n\n\n<p>PUREX (Plutonium Uranium Extraction) er en kemisk proces, der anvendes til at udvinde plutonium og uran fra brugt br\u00e6ndsel i nukleare reaktorer til produktionen af Mixed Oxide Fuel (MOX) br\u00e6ndsel som kan genbruges i en reaktor. De resterende fissionsprodukter og transuraner som reelt er affald, fylder nu fylder meget mindre og derfor kan deponeres langt billigere [1].<\/p>\n\n\n\n<p>PUREX-metoden er en af de mest udbredte metode. Den anvendes ved Orano-anl\u00e6gget i La Hague i Frankrig. Ligeledes i Japan og Rusland.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Trin i PUREX-processen<\/strong><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Opdelingsproces (shearing)<\/strong><\/h4>\n\n\n\n<p>F\u00f8rst fjernes endestykkerne af br\u00e6ndselselementerne, da de kan indeholde mere radioaktive materialer og har en h\u00f8jere varmeudvikling. <\/p>\n\n\n\n<p>Efter fjernelse af ende stykkerne klippes resten af br\u00e6ndselselementerne ud i mindre stykker med en l\u00e6ngde p\u00e5 typisk 35 millimeter. Denne opdeling i mindre stykker letter senere trin i oparbejdningsprocessen, hvor ekstraktion og behandling af de genanvendelige materialer, s\u00e5som uran og plutonium, forekommer.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Opbl\u00f8dning (Leaching)<\/strong><\/h4>\n\n\n\n<p>De opdelte br\u00e6ndselsstykker placeres i et opl\u00f8sningsmiddel, normalt en st\u00e6rkt oxidationsmiddel som salpetersyre (HNO3). Opl\u00f8sningsmidlet reagerer med br\u00e6ndslet og opl\u00f8ser de \u00f8nskede materialer, s\u00e5som plutonium og uran, det danner en opl\u00f8sning kaldet &#8220;br\u00e6ndselsopl\u00f8sning<\/p>\n\n\n\n<p>Opl\u00f8sningen indeholder genanvendelig uran (U), plutonium (Pu) og ikke-genanvendelig fissionsprodukter (Fp) som reelt er affald.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"330\" height=\"383\" src=\"https:\/\/www.atomkraft-jatak.dk\/newsite\/wp-content\/uploads\/2023\/08\/image-26.png\" alt=\"\" class=\"wp-image-29418\" srcset=\"https:\/\/www.atomkraft-jatak.dk\/newsite\/wp-content\/uploads\/2023\/08\/image-26.png 330w, https:\/\/www.atomkraft-jatak.dk\/newsite\/wp-content\/uploads\/2023\/08\/image-26-258x300.png 258w\" sizes=\"(max-width: 330px) 100vw, 330px\" \/><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Ekstraktion &#8211; adskille uran og plutonium fra fissionsprodukterne<\/strong><\/h4>\n\n\n\n<p>N\u00e6ste skridt er at adskille uran og plutonium fra fissionsprodukterne. Dette opn\u00e5s ved at blande opl\u00f8sningen med et kemisk stof kaldet tributylphosphat (TBP). N\u00e5r opl\u00f8sningen blandes med TBP, dannes der stabile komplekse forbindelser, hvorved uran (U) og plutonium (Pu) absorberes og adskilles fra fissionsprodukterne (Fp)<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/www.atomkraft-jatak.dk\/newsite\/wp-content\/uploads\/2023\/08\/image-21.png\" alt=\"\" class=\"wp-image-29299\" width=\"646\" height=\"374\" srcset=\"https:\/\/www.atomkraft-jatak.dk\/newsite\/wp-content\/uploads\/2023\/08\/image-21.png 750w, https:\/\/www.atomkraft-jatak.dk\/newsite\/wp-content\/uploads\/2023\/08\/image-21-300x174.png 300w, https:\/\/www.atomkraft-jatak.dk\/newsite\/wp-content\/uploads\/2023\/08\/image-21-360x208.png 360w, https:\/\/www.atomkraft-jatak.dk\/newsite\/wp-content\/uploads\/2023\/08\/image-21-600x347.png 600w\" sizes=\"(max-width: 646px) 100vw, 646px\" \/><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Stripping &#8211; adskille af uran og plutonium<\/strong><\/h4>\n\n\n\n<p>Stripping-trinnet indeb\u00e6rer at adskille uran fra plutonium. Det g\u00f8res ved hj\u00e6lp af en kombination af salpetersyre (HNO3) og en reducerende agent som f.eks. hydrazin (N2H4).<\/p>\n\n\n\n<p>Salpetersyren frig\u00f8re uranet og plutoniummet fra de organiske opl\u00f8sningsmidler, der blev brugt i ekstraktionsfasen. Mens hydrazin (N2H4) bruges til at reducere uranet til en lavere oxidationstilstand, hvilket f\u00f8rer til dannelsen af \u200b\u200bfast uran, mens plutoniummet forbliver i opl\u00f8sningen.<\/p>\n\n\n\n<p>Resultatet er en adskilt fase, hvor uranet er i form af urannitratkomplekser, og plutoniummet forbliver i det reducerede ekstraktionsmiddel.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Slutproduktet fra PUREX<\/strong><\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"540\" src=\"https:\/\/www.atomkraft-jatak.dk\/newsite\/wp-content\/uploads\/2023\/08\/image-23-1024x540.png\" alt=\"\" class=\"wp-image-29363\" srcset=\"https:\/\/www.atomkraft-jatak.dk\/newsite\/wp-content\/uploads\/2023\/08\/image-23-1024x540.png 1024w, https:\/\/www.atomkraft-jatak.dk\/newsite\/wp-content\/uploads\/2023\/08\/image-23-300x158.png 300w, https:\/\/www.atomkraft-jatak.dk\/newsite\/wp-content\/uploads\/2023\/08\/image-23-768x405.png 768w, https:\/\/www.atomkraft-jatak.dk\/newsite\/wp-content\/uploads\/2023\/08\/image-23-360x190.png 360w, https:\/\/www.atomkraft-jatak.dk\/newsite\/wp-content\/uploads\/2023\/08\/image-23-600x316.png 600w, https:\/\/www.atomkraft-jatak.dk\/newsite\/wp-content\/uploads\/2023\/08\/image-23.png 1210w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Genanvendelige materialer<\/strong><\/h4>\n\n\n\n<p>Efter gennemg\u00e5ende en PUREX-proces kan op til 95% af det brugte kernebr\u00e6ndsel genanvendes til at producere nyt br\u00e6ndsel s\u00e5kaldt Mixed Oxide Fuel (MOX) br\u00e6ndsel. Det er oftest i et blandingsforhold 70% genbrugt MOX og 30% nyt br\u00e6ndsel. Det kan spaltes igen og den endelige lagerm\u00e6ngde halveres s\u00e5ledes, samtidig med at energigevinsten fordobles. <\/p>\n\n\n\n<p>Efter PUREX-processen udg\u00f8r de ikke-genanvendelige materialer omkring 5% af det oprindelige brugte br\u00e6ndsel. Disse omfatter fissionprodukter, aktinider. Dog kan de kommende Generation IV-reaktorteknologier genbruge aktiniderne.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Fissionsprodukter til medicinske form\u00e5l.<\/strong><\/h4>\n\n\n\n<p>Nogle fissionsprodukterne afskilt i PUREX kan have nyttige egenskaber. Der kan v\u00e6re fors\u00f8g p\u00e5 at udvikle teknologier til at udnytte visse fissionsprodukter til medicinske form\u00e5l.<\/p>\n\n\n\n<p>Et eksempel er technetium-99m (Tc-99m). Det er en af de mest anvendte isotoper inden for nuklearmedicin til diagnoseform\u00e5l. Det genereres normalt ved at bestr\u00e5le naturligt uran-235 (U-235) i en fissionreaktor og derefter udf\u00f8re en kemisk proces for at adskille og rense Tc-99m fra resten af fissionsprodukterne.<\/p>\n\n\n\n<p>En anden kendt fissionsisotop med potentielle medicinske anvendelser er jod-131 (I-131). Dette radioaktive isotop kan anvendes i behandlingen af skjoldbruskkirtelsygdomme, s\u00e5som hypertyreose og visse typer af skjoldbruskkirtelkr\u00e6ft. I-131 udsender betastr\u00e5ling, der kan \u00f8del\u00e6gge skjoldbruskkirtelv\u00e6v, herunder kr\u00e6ftceller.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>PUREX \u00f8ger ikke proliferation<\/strong><\/h3>\n\n\n\n<p>PUREX-processen skaber ikke v\u00e5benkvalitets plutonium (Pu). Selvom metoden udvinder plutonium, vil det stadig indeholde en blanding af isotoper, herunder Pu-239, Pu-240 og andre plutoniumisotoper. For at producere v\u00e5benkvalitets plutonium med h\u00f8j renhed og lavt indhold af u\u00f8nskede isotoper som Pu-240, er der behov for yderligere trin, s\u00e5som kemisk oprensning og opkoncentrering. <\/p>\n\n\n\n<p>For at producere plutonium til brug i v\u00e5benprogrammer kr\u00e6ves en mere avanceret og specialiseret proces kaldet isotopskilning. Dette indeb\u00e6rer flere trin af kemisk behandling, oprensning og opkoncentrering for at opn\u00e5 plutonium med en meget h\u00f8j koncentration af Pu-239 og et lavt indhold af andre isotoper.<\/p>\n\n\n\n<p>Denne er ikke involveret i genbehandling og genbrug af brugt reaktorbr\u00e6ndsel.<\/p>\n\n\n\n<p>L\u00e6s mere om hvorfor <a href=\"https:\/\/www.atomkraft-jatak.dk\/newsite\/dokumenter\/paastand-atomkraft-giver-flere-atomvaaben\/\">atomkraft ikke giver flere atomv\u00e5ben<\/a><\/p>\n\n\n\n<p>Kilder<\/p>\n\n\n\n<ol>\n<li><a href=\"https:\/\/world-nuclear.org\/information-library\/nuclear-fuel-cycle\/fuel-recycling\/processing-of-used-nuclear-fuel.aspx\">Processing of Used Nuclear Fuel &#8211; World Nuclear Association (world-nuclear.org)<\/a><\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>Indledning PUREX (Plutonium Uranium Extraction) er en kemisk proces, der anvendes til at udvinde plutonium og uran fra brugt br\u00e6ndsel i nukleare reaktorer til produktionen af Mixed Oxide Fuel (MOX) br\u00e6ndsel som kan genbruges i en reaktor. De resterende fissionsprodukter og transuraner som reelt er affald, fylder nu fylder meget mindre og derfor kan deponeres &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/www.atomkraft-jatak.dk\/newsite\/dokumenter\/purex-genbehandlingsmetode\/\"> <span class=\"screen-reader-text\">PUREX &#8211; genbehandlingsmetoden<\/span> L\u00e6s mere &raquo;<\/a><\/p>\n","protected":false},"author":1297,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"doc_category":[78],"doc_tag":[],"year_month":"2026-07","word_count":730,"total_views":"190","reactions":{"happy":"0","normal":"0","sad":"0"},"author_info":{"author_nicename":"christian","author_url":"https:\/\/www.atomkraft-jatak.dk\/newsite\/author\/christian\/"},"doc_category_info":[{"term_name":"Atomaffald","term_url":"https:\/\/www.atomkraft-jatak.dk\/newsite\/docs-kategori\/atomaffald\/"}],"doc_tag_info":[],"author_list":[{"ID":"1180","user_login":"aage.gundelund antonsen","display_name":"\u00c5ge Gundelund Antonsen","id":"1180"},{"ID":"224","user_login":"adam.bertelsen","display_name":"Adam Bertelsen","id":"224"},{"ID":"419","user_login":"adam.hoffmann klingest","display_name":"Adam Hoffmann Klingest","id":"419"},{"ID":"1160","user_login":"adam.szok","display_name":"adam szok","id":"1160"},{"ID":"1","user_login":"admin","display_name":"admin","id":"1"},{"ID":"1140","user_login":"adrian.hove-kreutzfeldt","display_name":"Adrian Hove-Kreutzfeldt","id":"1140"},{"ID":"932","user_login":"aksel tarras.madsen","display_name":"Aksel Tarras Madsen","id":"932"},{"ID":"648","user_login":"alan.rasmussen","display_name":"Alan Rasmussen","id":"648"},{"ID":"432","user_login":"albert.mosegaard","display_name":"Albert Mosegaard","id":"432"},{"ID":"977","user_login":"alexander johan.olsen","display_name":"Alexander Johan Olsen","id":"977"},{"ID":"950","user_login":"alexander skjold.jasper","display_name":"Alexander Skjold Jasper","id":"950"},{"ID":"501","user_login":"alexander.hardarson","display_name":"Alexander Hardarson","id":"501"},{"ID":"692","user_login":"alexander.meldgaard","display_name":"Alexander Meldgaard","id":"692"},{"ID":"52","user_login":"alexander.mittet","display_name":"Alexander Mittet","id":"52"},{"ID":"804","user_login":"alexander.svendsen","display_name":"Alexander Svendsen","id":"804"},{"ID":"139","user_login":"allan haugaard.hansen","display_name":"Allan Haugaard Hansen","id":"139"},{"ID":"1148","user_login":"allan juul.larsen","display_name":"Allan Juul Larsen","id":"1148"},{"ID":"639","user_login":"allan.glasdam","display_name":"Allan Glasdam","id":"639"},{"ID":"1183","user_login":"allan.hansen","display_name":"Allan Hansen","id":"1183"},{"ID":"843","user_login":"allan.larsen","display_name":"Allan Larsen","id":"843"},{"ID":"245","user_login":"allan.nielsen","display_name":"Allan Nielsen","id":"245"},{"ID":"604","user_login":"allan.nielsen-0016","display_name":"Allan Nielsen","id":"604"},{"ID":"1127","user_login":"amanda.christiansen","display_name":"Amanda Christiansen","id":"1127"},{"ID":"1305","user_login":"amira.tarek@rpmanetworks.com","display_name":"Amira Tareq","id":"1305"},{"ID":"594","user_login":"anders bjarnoe.rasmussen","display_name":"Anders Bjarn\u00f8 Rasmussen","id":"594"},{"ID":"177","user_login":"anders leth.lee","display_name":"Anders Leth Lee","id":"177"},{"ID":"699","user_login":"anders lindegaard.nielsen","display_name":"Anders Lindegaard Nielsen","id":"699"},{"ID":"95","user_login":"anders.boejstrup","display_name":"Anders B\u00f8jstrup","id":"95"},{"ID":"1193","user_login":"anders.boel","display_name":"Anders Boel","id":"1193"},{"ID":"460","user_login":"anders.boye knudsen","display_name":"Anders Boye Knudsen","id":"460"},{"ID":"818","user_login":"anders.christensen","display_name":"Anders Christensen","id":"818"},{"ID":"877","user_login":"anders.enne jensen","display_name":"Anders Enn\u00e9 Jensen","id":"877"},{"ID":"902","user_login":"anders.fischer","display_name":"Anders Fischer","id":"902"},{"ID":"445","user_login":"anders.frost sloth","display_name":"Anders Frost Sloth","id":"445"},{"ID":"833","user_login":"anders.hegelskov","display_name":"Anders Hegelskov","id":"833"},{"ID":"779","user_login":"anders.heick","display_name":"Anders Heick","id":"779"},{"ID":"948","user_login":"anders.johansen","display_name":"Anders Johansen","id":"948"},{"ID":"1177","user_login":"anders.kildedal","display_name":"Anders Kildedal","id":"1177"},{"ID":"1012","user_login":"anders.kragelund","display_name":"Anders Kragelund","id":"1012"},{"ID":"180","user_login":"anders.lejre","display_name":"Anders Lejre","id":"180"},{"ID":"1125","user_login":"anders.liebst","display_name":"Anders Liebst","id":"1125"},{"ID":"844","user_login":"anders.lindholt","display_name":"Anders Lindholt","id":"844"},{"ID":"1080","user_login":"anders.loebger","display_name":"Anders L\u00f8bger","id":"1080"},{"ID":"1285","user_login":"anders.moeller","display_name":"Anders M\u00f8ller","id":"1285"},{"ID":"123","user_login":"anders.soevndahl","display_name":"Anders S\u00f8vndahl","id":"123"},{"ID":"945","user_login":"anders.staehr","display_name":"Anders St\u00e6hr","id":"945"},{"ID":"1222","user_login":"andreas hagerup.linnet","display_name":"Andreas Hagerup Linnet","id":"1222"},{"ID":"1051","user_login":"andreas.baerentzen","display_name":"Andreas B\u00e6rentzen","id":"1051"},{"ID":"284","user_login":"andreas.brahe","display_name":"Andreas Brahe","id":"284"},{"ID":"113","user_login":"andreas.heger biilmann","display_name":"Andreas Heger Biilmann","id":"113"},{"ID":"474","user_login":"andreas.linnet","display_name":"Andreas Linnet","id":"474"},{"ID":"480","user_login":"andreas.lundgaard","display_name":"Andreas Lundgaard","id":"480"},{"ID":"1149","user_login":"andreas.ranch","display_name":"Andreas Ranch","id":"1149"},{"ID":"540","user_login":"andreas.roed","display_name":"Andreas Roed","id":"540"},{"ID":"609","user_login":"andreas.vestergaard","display_name":"Andreas Vestergaard","id":"609"},{"ID":"824","user_login":"anette corydon.oest","display_name":"Anette Corydon Oest","id":"824"},{"ID":"1099","user_login":"anette.agerboe da rosa","display_name":"Anette Agerboe da Rosa","id":"1099"},{"ID":"1252","user_login":"anne lykke.soerensen","display_name":"Anne Lykke S\u00f8rensen","id":"1252"},{"ID":"1246","user_login":"annette sofia.skotte","display_name":"Annette Sofia Skotte","id":"1246"},{"ID":"805","user_login":"annette.davidsen","display_name":"Annette Davidsen","id":"805"},{"ID":"922","user_login":"annette.haagen","display_name":"Annette Haagen","id":"922"},{"ID":"1150","user_login":"annette.madsen","display_name":"Annette Madsen","id":"1150"},{"ID":"1168","user_login":"annette.randloev","display_name":"Annette Randl\u00f8v","id":"1168"},{"ID":"289","user_login":"annette.tvede","display_name":"Annette Tvede","id":"289"},{"ID":"820","user_login":"anton soegaard.poulsen","display_name":"Anton S\u00f8gaard Poulsen","id":"820"},{"ID":"1040","user_login":"anton.bastholm truelsen","display_name":"Anton Bastholm Truelsen","id":"1040"},{"ID":"149","user_login":"anton.michelsen","display_name":"Anton Michelsen","id":"149"},{"ID":"815","user_login":"arne.olson","display_name":"Arne Olson","id":"815"},{"ID":"147","user_login":"arne.thomsen","display_name":"Arne Thomsen","id":"147"},{"ID":"821","user_login":"asbjoern.brix-thomsen","display_name":"Asbj\u00f8rn Brix-Thomsen","id":"821"},{"ID":"567","user_login":"asbjoern.paulsen","display_name":"Asbj\u00f8rn Paulsen","id":"567"},{"ID":"975","user_login":"asger.damm","display_name":"Asger Damm","id":"975"},{"ID":"266","user_login":"asger.grundahl","display_name":"Asger Grundahl","id":"266"},{"ID":"944","user_login":"asger.noergaard","display_name":"Asger N\u00f8rgaard","id":"944"},{"ID":"1197","user_login":"asger.wium","display_name":"Asger Wium","id":"1197"},{"ID":"282","user_login":"aske.boettger","display_name":"Aske B\u00f8ttger","id":"282"},{"ID":"253","user_login":"aske.sonne","display_name":"Aske Sonne","id":"253"},{"ID":"469","user_login":"aslak holm.brunvand","display_name":"Aslak Holm Brunvand","id":"469"},{"ID":"654","user_login":"atos.andersen","display_name":"Atos Andersen","id":"654"},{"ID":"259","user_login":"august.harry soerinius","display_name":"August Harry S\u00f8rinius","id":"259"},{"ID":"1116","user_login":"bardur.poulsen","display_name":"Bardur Poulsen","id":"1116"},{"ID":"691","user_login":"benjamin.crawford","display_name":"Benjamin Crawford","id":"691"},{"ID":"122","user_login":"benny benjamin.hesselvig","display_name":"Benny Benjamin Hesselvig","id":"122"},{"ID":"813","user_login":"benny.olsen","display_name":"Benny Olsen","id":"813"},{"ID":"63","user_login":"benny.rasmussen","display_name":"Benny Rasmussen","id":"63"},{"ID":"133","user_login":"bent.jensen","display_name":"Bent Jensen","id":"133"},{"ID":"391","user_login":"bent.kjellerup","display_name":"BENT KJELLERUP","id":"391"},{"ID":"435","user_login":"bent.martinussen","display_name":"Bent Martinussen","id":"435"},{"ID":"849","user_login":"bent.outzen","display_name":"Bent Outzen","id":"849"},{"ID":"231","user_login":"bent.steffensen","display_name":"Bent Steffensen","id":"231"},{"ID":"161","user_login":"bente.lauridsen","display_name":"Bente Lauridsen","id":"161"},{"ID":"258","user_login":"berth.larsen","display_name":"Berth Larsen","id":"258"},{"ID":"715","user_login":"bertram.salomonsen","display_name":"Bertram Salomonsen","id":"715"},{"ID":"409","user_login":"bibbi.walsh","display_name":"Bibbi Walsh","id":"409"},{"ID":"230","user_login":"birger holm.broendberg","display_name":"Birger Holm Br\u00f8ndberg","id":"230"},{"ID":"854","user_login":"birgit.kohsel","display_name":"Birgit Kohsel","id":"854"},{"ID":"713","user_login":"bjarke nimb.marcher","display_name":"Bjarke Nimb M\u00e4rcher","id":"713"},{"ID":"74","user_login":"bjarke.moerch","display_name":"Bjarke M\u00f8rch","id":"74"},{"ID":"1287","user_login":"bjarne bach.nielsen","display_name":"Bjarne Bach Nielsen","id":"1287"},{"ID":"169","user_login":"bjarne.jensen","display_name":"Bjarne Jensen","id":"169"},{"ID":"649","user_login":"bjarne.lauridsen","display_name":"Bjarne Lauridsen","id":"649"},{"ID":"1029","user_login":"bjarne.molin","display_name":"Bjarne Molin","id":"1029"},{"ID":"1002","user_login":"bjarne.soerensen","display_name":"Bjarne S\u00f8rensen","id":"1002"},{"ID":"11","user_login":"bjarne.thorsted","display_name":"Bjarne Thorsted","id":"11"},{"ID":"582","user_login":"bjoern li kruse.rasmussen","display_name":"Bj\u00f8rn Li Kruse Rasmussen","id":"582"},{"ID":"39","user_login":"bjoern.dissing","display_name":"Bj\u00f8rn Dissing","id":"39"},{"ID":"618","user_login":"bjoern.kjerulf","display_name":"Bj\u00f8rn Kjerulf","id":"618"},{"ID":"1047","user_login":"bo paivinen.ullersted","display_name":"Bo Paivinen Ullersted","id":"1047"},{"ID":"959","user_login":"bo.barckman","display_name":"Bo Barckman","id":"959"},{"ID":"517","user_login":"bo.koertsen","display_name":"bo koertsen","id":"517"},{"ID":"117","user_login":"bo.lundqvist","display_name":"Bo Lundqvist","id":"117"},{"ID":"901","user_login":"bo.tranberg","display_name":"Bo Tranberg","id":"901"},{"ID":"951","user_login":"bo.vaaben","display_name":"Bo Vaaben","id":"951"},{"ID":"57","user_login":"boerge rostgaard.winkel","display_name":"B\u00f8rge Rostgaard Winkel","id":"57"},{"ID":"919","user_login":"brian.bech laursen","display_name":"Brian Bech Laursen","id":"919"},{"ID":"1189","user_login":"brian.christensen","display_name":"Brian Christensen","id":"1189"},{"ID":"728","user_login":"brian.madsen","display_name":"Brian Madsen","id":"728"},{"ID":"987","user_login":"brian.olsen","display_name":"Brian Olsen","id":"987"},{"ID":"115","user_login":"brian.soerensen","display_name":"Brian S\u00f8rensen","id":"115"},{"ID":"61","user_login":"brian.stjernholm","display_name":"Brian Stjernholm","id":"61"},{"ID":"89","user_login":"brian.urth","display_name":"Brian Urth","id":"89"},{"ID":"287","user_login":"camilla.soltau","display_name":"Camilla Soltau","id":"287"},{"ID":"653","user_login":"camilla.winkel","display_name":"Camilla Winkel","id":"653"},{"ID":"863","user_login":"carl.hoegstedt","display_name":"Carl H\u00f8gstedt","id":"863"},{"ID":"730","user_login":"carl.oestervig","display_name":"Carl \u00d8stervig","id":"730"},{"ID":"155","user_login":"caroline.raundahl","display_name":"Caroline Raundahl","id":"155"},{"ID":"659","user_login":"carsten dreisig.hansen","display_name":"Carsten Dreisig Hansen","id":"659"},{"ID":"837","user_login":"carsten.andreasen","display_name":"Carsten Andreasen","id":"837"},{"ID":"999","user_login":"carsten.laurberg","display_name":"Carsten Laurberg","id":"999"},{"ID":"1154","user_login":"carsten.lindberg","display_name":"Carsten Lindberg","id":"1154"},{"ID":"588","user_login":"carsten.lundberg","display_name":"carsten Lundberg","id":"588"},{"ID":"625","user_login":"carsten.sand","display_name":"Carsten Sand","id":"625"},{"ID":"532","user_login":"carsten.toft-hansen","display_name":"Carsten Toft-Hansen","id":"532"},{"ID":"1082","user_login":"casper.hagelskaer","display_name":"Casper Hagelsk\u00e6r","id":"1082"},{"ID":"882","user_login":"casper.juul lorentzen","display_name":"Casper Juul Lorentzen","id":"882"},{"ID":"225","user_login":"casper.lindbeck","display_name":"Casper Lindbeck","id":"225"},{"ID":"530","user_login":"casper.panduro","display_name":"Casper Panduro","id":"530"},{"ID":"974","user_login":"casper.winkel","display_name":"Casper Winkel","id":"974"},{"ID":"42","user_login":"charlotte.sollid","display_name":"Charlotte Sollid","id":"42"},{"ID":"559","user_login":"charly.hessellund","display_name":"Charly Hessellund","id":"559"},{"ID":"1297","user_login":"Christian","display_name":"Chris","id":"1297"},{"ID":"703","user_login":"christian helledie.vandkrog","display_name":"Christian Helledie Vandkrog","id":"703"},{"ID":"508","user_login":"christian.badsted","display_name":"Christian Badsted","id":"508"},{"ID":"1243","user_login":"christian.bechmann","display_name":"Christian Bechmann","id":"1243"},{"ID":"798","user_login":"christian.bredgaard","display_name":"Christian Bredgaard","id":"798"},{"ID":"1259","user_login":"christian.brochstedt","display_name":"Christian Brochstedt","id":"1259"},{"ID":"148","user_login":"christian.carlsen","display_name":"Christian Carlsen","id":"148"},{"ID":"458","user_login":"christian.frederiksen","display_name":"Christian Frederiksen","id":"458"},{"ID":"580","user_login":"christian.hejesen","display_name":"Christian Hejesen","id":"580"},{"ID":"1008","user_login":"christian.hersnaes","display_name":"Christian Hersn\u00e6s","id":"1008"},{"ID":"1036","user_login":"christian.joergensen","display_name":"Christian J\u00f8rgensen","id":"1036"},{"ID":"599","user_login":"christian.kulmbak","display_name":"Christian Kulmbak","id":"599"},{"ID":"1191","user_login":"christian.lundmand","display_name":"Christian Lundmand","id":"1191"},{"ID":"397","user_login":"christian.rasmussen","display_name":"Christian Rasmussen","id":"397"},{"ID":"595","user_login":"christian.rasmussen-2952","display_name":"Christian Rasmussen","id":"595"},{"ID":"544","user_login":"christian.schultz","display_name":"Christian Schultz","id":"544"},{"ID":"1270","user_login":"christian.toft","display_name":"Christian Toft","id":"1270"},{"ID":"389","user_login":"christian.tramm","display_name":"Christian Tramm","id":"389"},{"ID":"838","user_login":"christian.vestergaard","display_name":"Christian Vestergaard","id":"838"},{"ID":"1233","user_login":"christian.von wendt-jensen","display_name":"Christian von Wendt-Jensen","id":"1233"},{"ID":"827","user_login":"christina.dahl jakobsen","display_name":"Christina Dahl Jakobsen","id":"827"},{"ID":"1303","user_login":"christoffer","display_name":"christoffer Ravn","id":"1303"},{"ID":"60","user_login":"christoffer.haug brinch","display_name":"Christoffer Haug Brinch","id":"60"},{"ID":"99","user_login":"christoffer.ravn","display_name":"Christoffer Ravn","id":"99"},{"ID":"1253","user_login":"christoffer.veng","display_name":"Christoffer Veng","id":"1253"},{"ID":"34","user_login":"claes.theilgaard","display_name":"Claes Theilgaard","id":"34"},{"ID":"931","user_login":"claus helge.nielsen","display_name":"Claus Helge Nielsen","id":"931"},{"ID":"340","user_login":"claus hvid.simonsen","display_name":"Claus Hvid Simonsen","id":"340"},{"ID":"303","user_login":"claus.abel","display_name":"CLAUS ABEL","id":"303"},{"ID":"537","user_login":"claus.andersen","display_name":"Claus Andersen","id":"537"},{"ID":"138","user_login":"claus.bulow","display_name":"Claus B\u00fclow","id":"138"},{"ID":"107","user_login":"claus.elholm","display_name":"Claus Elholm","id":"107"},{"ID":"592","user_login":"claus.futtrup","display_name":"Claus Futtrup","id":"592"},{"ID":"996","user_login":"claus.havboe","display_name":"Claus Havboe","id":"996"},{"ID":"221","user_login":"claus.henningsen","display_name":"Claus Henningsen","id":"221"},{"ID":"1090","user_login":"claus.hoeyer","display_name":"Claus H\u00f8yer","id":"1090"},{"ID":"729","user_login":"claus.moeller","display_name":"Claus M\u00f8ller","id":"729"},{"ID":"1136","user_login":"claus.moeller-0623","display_name":"Claus M\u00f8ller","id":"1136"},{"ID":"1096","user_login":"claus.munkholm","display_name":"Claus Munkholm","id":"1096"},{"ID":"565","user_login":"claus.poulsen","display_name":"Claus Poulsen","id":"565"},{"ID":"928","user_login":"claus.poulsen-2495","display_name":"Claus Poulsen","id":"928"},{"ID":"814","user_login":"claus.poulsen-6229","display_name":"Claus Poulsen","id":"814"},{"ID":"917","user_login":"claus.poulsen-9953","display_name":"Claus Poulsen","id":"917"},{"ID":"488","user_login":"claus.soeegaard","display_name":"Claus S\u00f8egaard","id":"488"},{"ID":"670","user_login":"claus.steffensen","display_name":"Claus Steffensen","id":"670"},{"ID":"476","user_login":"claus.vilstrup","display_name":"Claus Vilstrup","id":"476"},{"ID":"35","user_login":"claus.willen","display_name":"Claus Willen","id":"35"},{"ID":"1152","user_login":"cliff.hansen","display_name":"Cliff Hansen","id":"1152"},{"ID":"1276","user_login":"cornelius.olesen","display_name":"Cornelius Olesen","id":"1276"},{"ID":"240","user_login":"cristina.gustenhoff","display_name":"Cristina Gustenhoff","id":"240"},{"ID":"2","user_login":"CTO","display_name":"Johan","id":"2"},{"ID":"676","user_login":"dan kristoffer.holmstad","display_name":"Dan Kristoffer Holmstad","id":"676"},{"ID":"1260","user_login":"dan.suenson","display_name":"Dan Suenson","id":"1260"},{"ID":"1074","user_login":"daniel aagaard.rasmussen","display_name":"Daniel Aagaard Rasmussen","id":"1074"},{"ID":"741","user_login":"daniel.adrian","display_name":"Daniel Adrian","id":"741"},{"ID":"254","user_login":"daniel.dyrberg","display_name":"Daniel Dyrberg","id":"254"},{"ID":"866","user_login":"daniel.frykman","display_name":"Daniel Frykman","id":"866"},{"ID":"439","user_login":"daniel.klemmed nielsen","display_name":"Daniel Klemmed Nielsen","id":"439"},{"ID":"1020","user_login":"daniel.nielsen","display_name":"Daniel Nielsen","id":"1020"},{"ID":"619","user_login":"daniel.otykier","display_name":"Daniel Otykier","id":"619"},{"ID":"120","user_login":"david.bojsen","display_name":"David Bojsen","id":"120"},{"ID":"982","user_login":"david.brasholt","display_name":"David Brasholt","id":"982"},{"ID":"585","user_login":"david.hoejelsen","display_name":"David H\u00f8jelsen","id":"585"},{"ID":"839","user_login":"david.hoejgaard","display_name":"David H\u00f8jgaard","id":"839"},{"ID":"1143","user_login":"david.moritz","display_name":"David Moritz","id":"1143"},{"ID":"290","user_login":"david.nestved","display_name":"David Nestved","id":"290"},{"ID":"822","user_login":"david.rudberg","display_name":"David rudberg","id":"822"},{"ID":"338","user_login":"dehli.joergen krohn","display_name":"Dehli J\u00f8rgen Krohn","id":"338"},{"ID":"737","user_login":"dennis.nielsen","display_name":"Dennis Nielsen","id":"737"},{"ID":"1271","user_login":"dennis.pedersen","display_name":"Dennis Pedersen","id":"1271"},{"ID":"781","user_login":"dennis.soerensen","display_name":"Dennis S\u00f8rensen","id":"781"},{"ID":"867","user_login":"dennis.vaeversted","display_name":"Dennis V\u00e6versted","id":"867"},{"ID":"267","user_login":"dennis.vestergaard","display_name":"dennis vestergaard","id":"267"},{"ID":"203","user_login":"dennis.zachariasen","display_name":"Dennis Zachariasen","id":"203"},{"ID":"272","user_login":"dirch.fischer","display_name":"Dirch Fischer","id":"272"},{"ID":"248","user_login":"dorte grinsted.curtz","display_name":"Dorte Grinsted Curtz","id":"248"},{"ID":"521","user_login":"dorthe.geday","display_name":"Dorthe Geday","id":"521"},{"ID":"1251","user_login":"ebbe.nielsen","display_name":"Ebbe Nielsen","id":"1251"},{"ID":"1236","user_login":"ebbe.nordbo","display_name":"ebbe nordbo","id":"1236"},{"ID":"1204","user_login":"egon.soerensen","display_name":"Egon S\u00f8rensen","id":"1204"},{"ID":"66","user_login":"eik.roenfeldt","display_name":"Eik R\u00f8nfeldt","id":"66"},{"ID":"370","user_login":"ejnar maare.soendergaard","display_name":"Ejnar Maare S\u00f8ndergaard","id":"370"},{"ID":"857","user_login":"ejnar.haakonsen","display_name":"Ejnar H\u00e5konsen","id":"857"},{"ID":"913","user_login":"elias.andersen","display_name":"Elias Andersen","id":"913"},{"ID":"1254","user_login":"elias.christensen","display_name":"Elias Christensen","id":"1254"},{"ID":"142","user_login":"elias.finseth","display_name":"Elias Finseth","id":"142"},{"ID":"1145","user_login":"elsebet.jensen","display_name":"Elsebet Jensen","id":"1145"},{"ID":"760","user_login":"elsebeth.westmark","display_name":"Elsebeth Westmark","id":"760"},{"ID":"56","user_login":"emil folmer.heltoft","display_name":"Emil Folmer Heltoft","id":"56"},{"ID":"763","user_login":"emil vest.hansen","display_name":"Emil Vest Hansen","id":"763"},{"ID":"1209","user_login":"emil.bahnson","display_name":"Emil Bahnson","id":"1209"},{"ID":"1078","user_login":"emil.kozuch","display_name":"Emil Kozuch","id":"1078"},{"ID":"1147","user_login":"emil.lauridsen","display_name":"Emil Lauridsen","id":"1147"},{"ID":"359","user_login":"emil.stenboeg","display_name":"Emil Stenb\u00f8g","id":"359"},{"ID":"518","user_login":"emil.traidl","display_name":"Emil Traidl","id":"518"},{"ID":"1087","user_login":"emil.westmark","display_name":"Emil Westmark","id":"1087"},{"ID":"1142","user_login":"emilie.ravens","display_name":"Emilie Ravens","id":"1142"},{"ID":"345","user_login":"eric.bramsen","display_name":"Eric Bramsen","id":"345"},{"ID":"466","user_login":"erik.bastiansen","display_name":"Erik Bastiansen","id":"466"},{"ID":"591","user_login":"erik.broendsted","display_name":"Erik Br\u00f8ndsted","id":"591"},{"ID":"562","user_login":"erik.elkhoej","display_name":"Erik Elkh\u00f8j","id":"562"},{"ID":"64","user_login":"erik.hviid","display_name":"Erik Hviid","id":"64"},{"ID":"1214","user_login":"erik.nielsen","display_name":"Erik Nielsen","id":"1214"},{"ID":"31","user_login":"erik.schou","display_name":"Erik Schou","id":"31"},{"ID":"725","user_login":"erik.tiedgen","display_name":"Erik Tiedgen","id":"725"},{"ID":"1181","user_login":"erling joergensen.joergensen","display_name":"Erling J\u00f8rgensen J\u00f8rgensen","id":"1181"},{"ID":"726","user_login":"erling.engmark","display_name":"Erling Engmark","id":"726"},{"ID":"1038","user_login":"erling.markussen","display_name":"Erling Markussen","id":"1038"},{"ID":"1273","user_login":"ernst.lunding","display_name":"Ernst Lunding","id":"1273"},{"ID":"1133","user_login":"esben.christensen","display_name":"Esben Christensen","id":"1133"},{"ID":"269","user_login":"esben.hansen","display_name":"Esben Hansen","id":"269"},{"ID":"255","user_login":"eskild.herskind","display_name":"Eskild Herskind","id":"255"},{"ID":"739","user_login":"eskild.olsen","display_name":"Eskild Olsen","id":"739"},{"ID":"388","user_login":"esmaralda.garvang","display_name":"ESMARALDA garvang","id":"388"},{"ID":"534","user_login":"espen.jensen","display_name":"Espen Jensen","id":"534"},{"ID":"381","user_login":"esper.riis","display_name":"Esper Riis","id":"381"},{"ID":"563","user_login":"felix.uldbaek","display_name":"Felix Uld","id":"563"},{"ID":"459","user_login":"filip.pisinger","display_name":"Filip Pisinger","id":"459"},{"ID":"492","user_login":"finn.elholm","display_name":"Finn Elholm","id":"492"},{"ID":"329","user_login":"finn.hansen","display_name":"Finn Hansen","id":"329"},{"ID":"651","user_login":"finn.jensen","display_name":"Finn Jensen","id":"651"},{"ID":"408","user_login":"finn.skov","display_name":"Finn Skov","id":"408"},{"ID":"769","user_login":"flemming.drechsel","display_name":"Flemming Drechsel","id":"769"},{"ID":"1201","user_login":"flemming.kjaerup","display_name":"Flemming Kj\u00e6rup","id":"1201"},{"ID":"450","user_login":"flemming.schollert","display_name":"Flemming Schollert","id":"450"},{"ID":"307","user_login":"flemming.schwartz","display_name":"Flemming Schwartz","id":"307"},{"ID":"1224","user_login":"flemming.schwartz-0133","display_name":"Flemming Schwartz","id":"1224"},{"ID":"372","user_login":"foged.casper","display_name":"Foged Casper","id":"372"},{"ID":"442","user_login":"frank.andersen","display_name":"Frank Andersen","id":"442"},{"ID":"483","user_login":"frank.andersen-3137","display_name":"Frank Andersen","id":"483"},{"ID":"401","user_login":"frank.christiansen","display_name":"Frank Christiansen","id":"401"},{"ID":"27","user_login":"frank.skjoennemand","display_name":"Frank Skj\u00f8nnemand","id":"27"},{"ID":"566","user_login":"frank.skjoennemand emand","display_name":"Frank Skj\u00f8nnemand emand","id":"566"},{"ID":"561","user_login":"frank.weyergang","display_name":"Frank Weyergang","id":"561"},{"ID":"187","user_login":"frede.rahbek","display_name":"Frede Rahbek","id":"187"},{"ID":"1076","user_login":"frederik blirup.worm","display_name":"Frederik Blirup Worm","id":"1076"},{"ID":"44","user_login":"frederik gerner.andreasen","display_name":"Frederik Gerner Andreasen","id":"44"},{"ID":"47","user_login":"Frederik Jakob Hansen","display_name":"Frederik Jakob Hansen","id":"47"},{"ID":"1291","user_login":"frederik klakk.jeppesen","display_name":"Frederik Klakk Jeppesen","id":"1291"},{"ID":"1016","user_login":"frederik wurtz.soerensen","display_name":"Frederik W\u00fcrtz S\u00f8rensen","id":"1016"},{"ID":"636","user_login":"frederik.braad","display_name":"Frederik Braad","id":"636"},{"ID":"172","user_login":"frederik.bundgaard","display_name":"Frederik Bundgaard","id":"172"},{"ID":"124","user_login":"frederik.couppe","display_name":"Frederik Couppe","id":"124"},{"ID":"297","user_login":"frederik.damgaard","display_name":"Frederik Damgaard","id":"297"},{"ID":"1203","user_login":"frederik.hansen","display_name":"Frederik Hansen","id":"1203"},{"ID":"627","user_login":"frederik.joergensen","display_name":"Frederik J\u00f8rgensen","id":"627"},{"ID":"793","user_login":"frederik.kristensen","display_name":"Frederik Kristensen","id":"793"},{"ID":"545","user_login":"frederik.larseb","display_name":"Frederik Larseb","id":"545"},{"ID":"870","user_login":"frederik.lind-bendixen","display_name":"Frederik Lind-Bendixen","id":"870"},{"ID":"422","user_login":"frederik.lindhardt","display_name":"Frederik Lindhardt","id":"422"},{"ID":"750","user_login":"frederik.thorup","display_name":"Frederik Thorup","id":"750"},{"ID":"1132","user_login":"frej.troelsen","display_name":"Frej Troelsen","id":"1132"},{"ID":"900","user_login":"georg.petersen","display_name":"Georg Petersen","id":"900"},{"ID":"41","user_login":"gerda.petersen","display_name":"gerda petersen","id":"41"},{"ID":"859","user_login":"gert.andersen","display_name":"Gert Andersen","id":"859"},{"ID":"1208","user_login":"gert.nielsen","display_name":"Gert Nielsen","id":"1208"},{"ID":"71","user_login":"gert.svendsen","display_name":"Gert Svendsen","id":"71"},{"ID":"1018","user_login":"gert.wassard","display_name":"Gert Wassard","id":"1018"},{"ID":"925","user_login":"giacomo.lindorff","display_name":"Giacomo Lindorff","id":"925"},{"ID":"1170","user_login":"gitte.falk","display_name":"Gitte Falk","id":"1170"},{"ID":"511","user_login":"gregers.ibsen","display_name":"Gregers Ibsen","id":"511"},{"ID":"1065","user_login":"guillaume.nadon","display_name":"Guillaume Nadon","id":"1065"},{"ID":"513","user_login":"gustaf hyllested.serve","display_name":"Gustaf Hyllested Serve","id":"513"},{"ID":"1048","user_login":"gustav holm.kristensen","display_name":"Gustav Holm Kristensen","id":"1048"},{"ID":"1000","user_login":"gustav truels.hoeybye","display_name":"Gustav Truels H\u00f8ybye","id":"1000"},{"ID":"387","user_login":"gustav.sloth","display_name":"Gustav Sloth","id":"387"},{"ID":"910","user_login":"gustav.von der maase","display_name":"Gustav von der Maase","id":"910"},{"ID":"402","user_login":"hamad.mahmoud","display_name":"Hamad Mahmoud","id":"402"},{"ID":"1063","user_login":"hamuid.den 3","display_name":"hamuid den 3","id":"1063"},{"ID":"48","user_login":"hanne.tirsvad johannsen","display_name":"Hanne Tirsvad Johannsen","id":"48"},{"ID":"1283","user_login":"hanne.walbum","display_name":"Hanne Walbum","id":"1283"},{"ID":"539","user_login":"hans -joergen.skovgaard","display_name":"Hans -J\u00f8rgen Skovgaard","id":"539"},{"ID":"701","user_login":"hans christian.pedersen","display_name":"Hans Christian Pedersen","id":"701"},{"ID":"847","user_login":"hans christian.saustrup","display_name":"Hans Christian Saustrup","id":"847"},{"ID":"1032","user_login":"hans erik.gram","display_name":"Hans Erik Gram","id":"1032"},{"ID":"270","user_login":"hans henrik gerner.jensen","display_name":"Hans Henrik Gerner Jensen","id":"270"},{"ID":"555","user_login":"hans henrik.kampmann","display_name":"Hans Henrik Kampmann","id":"555"},{"ID":"325","user_login":"hans iver.schmidt","display_name":"Hans Iver Schmidt","id":"325"},{"ID":"765","user_login":"hans kristian.heinze","display_name":"Hans Kristian Heinze","id":"765"},{"ID":"690","user_login":"hans michael.hansen","display_name":"Hans Michael Hansen","id":"690"},{"ID":"92","user_login":"Hans Nielsen","display_name":"Hans J\u00f8rgen Nielsen","id":"92"},{"ID":"1173","user_login":"hans ole.olsen","display_name":"Hans Ole Olsen","id":"1173"},{"ID":"256","user_login":"hans peter.lausten-thomsen","display_name":"Hans Peter Lausten-Thomsen","id":"256"},{"ID":"192","user_login":"hans petter.dalen","display_name":"Hans Petter Dalen","id":"192"},{"ID":"1073","user_login":"hans tage.lund","display_name":"Hans Tage Lund","id":"1073"},{"ID":"753","user_login":"hans v..madsen","display_name":"Hans V. Madsen","id":"753"},{"ID":"90","user_login":"hans-christian.kromann","display_name":"Hans-Christian Kromann","id":"90"},{"ID":"330","user_login":"hans.amsinck","display_name":"Hans Amsinck","id":"330"},{"ID":"985","user_login":"hans.damm","display_name":"Hans Damm","id":"985"},{"ID":"548","user_login":"hans.fabrin","display_name":"Hans Fabrin","id":"548"},{"ID":"1007","user_login":"hans.frandsen","display_name":"Hans Frandsen","id":"1007"},{"ID":"379","user_login":"hans.fynbo","display_name":"Hans Fynbo","id":"379"},{"ID":"462","user_login":"hans.kjaersgaard","display_name":"Hans Kj\u00e6rsgaard","id":"462"},{"ID":"1034","user_login":"hans.knudsen","display_name":"Hans Knudsen","id":"1034"},{"ID":"1156","user_login":"hans.nis-hanssen","display_name":"Hans Nis-Hanssen","id":"1156"},{"ID":"785","user_login":"hans.noehr","display_name":"Hans N\u00f8hr","id":"785"},{"ID":"1178","user_login":"hans.thysen","display_name":"Hans Thysen","id":"1178"},{"ID":"423","user_login":"hans.uerkvitz","display_name":"Hans Uerkvitz","id":"423"},{"ID":"743","user_login":"hansen.knud","display_name":"Knud Hansen","id":"743"},{"ID":"682","user_login":"harald.frisch","display_name":"Harald Frisch","id":"682"},{"ID":"965","user_login":"hasse.koksbang","display_name":"Hasse Koksbang","id":"965"},{"ID":"1130","user_login":"heidi.gotfredsen","display_name":"Heidi Gotfredsen","id":"1130"},{"ID":"550","user_login":"heine.lynge","display_name":"Heine Lynge","id":"550"},{"ID":"1015","user_login":"heini.wedelgaard","display_name":"Heini Wedelg\u00e5rd","id":"1015"},{"ID":"166","user_login":"helle.loevgreen","display_name":"Helle L\u00f8vgreen","id":"166"},{"ID":"1238","user_login":"henning.bastian","display_name":"Henning Bastian","id":"1238"},{"ID":"24","user_login":"henning.hansen","display_name":"Henning hansen","id":"24"},{"ID":"452","user_login":"henning.therkildsen","display_name":"Henning Therkildsen","id":"452"},{"ID":"1211","user_login":"henriette.blaedel","display_name":"Henriette Bl\u00e6del","id":"1211"},{"ID":"30","user_login":"henriette.svendsen","display_name":"Henriette Svendsen","id":"30"},{"ID":"1153","user_login":"henrik goebel.fuchtbauer","display_name":"Henrik G\u00f8bel F\u00fcchtbauer","id":"1153"},{"ID":"1265","user_login":"henrik lyhne.jensen","display_name":"Henrik Lyhne Jensen","id":"1265"},{"ID":"1026","user_login":"henrik raeder.clausen","display_name":"Henrik R\u00e6der Clausen","id":"1026"},{"ID":"522","user_login":"henrik.bach","display_name":"Henrik Bach","id":"522"},{"ID":"84","user_login":"henrik.bille","display_name":"Henrik Bille","id":"84"},{"ID":"415","user_login":"henrik.bille-6600","display_name":"Henrik Bille","id":"415"},{"ID":"603","user_login":"henrik.blitger","display_name":"Henrik Blitger","id":"603"},{"ID":"295","user_login":"henrik.curtz","display_name":"Henrik Curtz","id":"295"},{"ID":"687","user_login":"henrik.dahl hermansen","display_name":"Henrik Dahl Hermansen","id":"687"},{"ID":"128","user_login":"henrik.friberg","display_name":"Henrik Friberg","id":"128"},{"ID":"623","user_login":"henrik.hestbech","display_name":"Henrik Hestbech","id":"623"},{"ID":"721","user_login":"henrik.huusom","display_name":"Henrik Huusom","id":"721"},{"ID":"755","user_login":"henrik.jakobsen","display_name":"Henrik Jakobsen","id":"755"},{"ID":"1120","user_login":"henrik.martinussen","display_name":"Henrik Martinussen","id":"1120"},{"ID":"1294","user_login":"henrik.moellerhoej","display_name":"Henrik M\u00f8llerh\u00f8j","id":"1294"},{"ID":"953","user_login":"henrik.morbjerg","display_name":"Henrik Morbjerg","id":"953"},{"ID":"301","user_login":"henrik.murmann","display_name":"Henrik Murmann","id":"301"},{"ID":"890","user_login":"henrik.nielsen","display_name":"Henrik Nielsen","id":"890"},{"ID":"581","user_login":"henrik.pedersen","display_name":"Henrik Pedersen","id":"581"},{"ID":"920","user_login":"henrik.ranum","display_name":"Henrik Ranum","id":"920"},{"ID":"1264","user_login":"henrik.stoerling","display_name":"Henrik St\u00f8rling","id":"1264"},{"ID":"309","user_login":"henrik.trolle","display_name":"Henrik Trolle","id":"309"},{"ID":"50","user_login":"hermann.haraldsson","display_name":"Hermann Haraldsson","id":"50"},{"ID":"164","user_login":"iago.storgaard","display_name":"Iago Storgaard","id":"164"},{"ID":"543","user_login":"ian.gottlieb","display_name":"Ian Gottlieb","id":"543"},{"ID":"803","user_login":"ian.stoettrup","display_name":"Ian St\u00f8ttrup","id":"803"},{"ID":"686","user_login":"ib.bech hansen","display_name":"Ib Bech Hansen","id":"686"},{"ID":"981","user_login":"ida.dinesen","display_name":"Ida Dinesen","id":"981"},{"ID":"145","user_login":"ida.lauridsen","display_name":"Ida Lauridsen","id":"145"},{"ID":"722","user_login":"ike houmann.nielsen","display_name":"Ike Houmann Nielsen","id":"722"},{"ID":"140","user_login":"ingolf.nielsen","display_name":"Ingolf Nielsen","id":"140"},{"ID":"1117","user_login":"ivan.sparvath","display_name":"Ivan Sparvath","id":"1117"},{"ID":"708","user_login":"iver.moeller","display_name":"Iver M\u00f8ller","id":"708"},{"ID":"993","user_login":"jacob philippe.svane","display_name":"Jacob Philippe Svane","id":"993"},{"ID":"1055","user_login":"jacob.andersen","display_name":"Jacob Andersen","id":"1055"},{"ID":"141","user_login":"jacob.dyrby petersen","display_name":"Jacob Dyrby Petersen","id":"141"},{"ID":"777","user_login":"jacob.fisker","display_name":"Jacob Fisker","id":"777"},{"ID":"110","user_login":"jacob.grindsted","display_name":"Jacob Grindsted","id":"110"},{"ID":"227","user_login":"jacob.hvass-larsen","display_name":"Jacob Hvass-Larsen","id":"227"},{"ID":"943","user_login":"jacob.kayser","display_name":"Jacob Kayser","id":"943"},{"ID":"1190","user_login":"jacob.koenig","display_name":"Jacob k\u00f8nig","id":"1190"},{"ID":"1035","user_login":"jacob.kristiansen","display_name":"Jacob Kristiansen","id":"1035"},{"ID":"697","user_login":"jacob.madsen","display_name":"Jacob Madsen","id":"697"},{"ID":"1175","user_login":"jacob.mejer nielsen","display_name":"Jacob Mejer Nielsen","id":"1175"},{"ID":"331","user_login":"jacob.prehn","display_name":"Jacob Prehn","id":"331"},{"ID":"333","user_login":"jacob.schmidt","display_name":"Jacob Schmidt","id":"333"},{"ID":"871","user_login":"jacob.van dijk","display_name":"Jacob van Dijk","id":"871"},{"ID":"176","user_login":"jacob.winther","display_name":"Jacob Winther","id":"176"},{"ID":"471","user_login":"jakob brendstrup.hansen","display_name":"Jakob Brendstrup Hansen","id":"471"},{"ID":"1064","user_login":"jakob fynsgaard.miles","display_name":"Jakob Fynsgaard Miles","id":"1064"},{"ID":"590","user_login":"jakob schoubye.poulsen","display_name":"Jakob Schoubye Poulsen","id":"590"},{"ID":"574","user_login":"jakob.damsgaard","display_name":"Jakob Damsgaard","id":"574"},{"ID":"62","user_login":"jakob.huusom","display_name":"Jakob Huusom","id":"62"},{"ID":"78","user_login":"jakob.huusom-0946","display_name":"Jakob Huusom","id":"78"},{"ID":"685","user_login":"jakob.jensen","display_name":"Jakob Jensen","id":"685"},{"ID":"994","user_login":"jakob.kofod beyer","display_name":"Jakob Kofod Beyer","id":"994"},{"ID":"214","user_login":"jakob.langkjaer","display_name":"Jakob Langkj\u00e6r","id":"214"},{"ID":"1213","user_login":"jakob.moeller","display_name":"Jakob M\u00f8ller","id":"1213"},{"ID":"640","user_login":"jakob.schytz","display_name":"Jakob Schytz","id":"640"},{"ID":"189","user_login":"jakob.soederberg","display_name":"jakob s\u00f8derberg","id":"189"},{"ID":"786","user_login":"jakobsen.anders","display_name":"Jakobsen Anders","id":"786"},{"ID":"10","user_login":"jan henrik.radl","display_name":"Jan Henrik Radl","id":"10"},{"ID":"876","user_login":"jan ritzau.frydensberg","display_name":"Jan Ritzau Frydensberg","id":"876"},{"ID":"516","user_login":"jan thilkjer.eriksen","display_name":"Jan Thilkjer Eriksen","id":"516"},{"ID":"617","user_login":"jan.bagi-pedersen","display_name":"Jan Bagi-Pedersen","id":"617"},{"ID":"1248","user_login":"jan.carlsen","display_name":"Jan Carlsen","id":"1248"},{"ID":"434","user_login":"jan.delff","display_name":"Jan Delff","id":"434"},{"ID":"58","user_login":"jan.frederiksen","display_name":"Jan Frederiksen","id":"58"},{"ID":"1053","user_login":"jan.greisen","display_name":"Jan Greisen","id":"1053"},{"ID":"18","user_login":"jan.hansen","display_name":"Jan Hansen","id":"18"},{"ID":"1268","user_login":"jan.mortensen","display_name":"Jan Mortensen","id":"1268"},{"ID":"1199","user_login":"jan.nielsen","display_name":"Jan Nielsen","id":"1199"},{"ID":"524","user_login":"jan.soenderby","display_name":"Jan S\u00f8nderby","id":"524"},{"ID":"279","user_login":"jan.veidiksen","display_name":"Jan Veidiksen","id":"279"},{"ID":"1042","user_login":"jan.warming","display_name":"Jan Warming","id":"1042"},{"ID":"745","user_login":"jannick.joergensen","display_name":"Jannick J\u00f8rgensen","id":"745"},{"ID":"510","user_login":"jannik.kargo christensen","display_name":"Jannik Kargo Christensen","id":"510"},{"ID":"1234","user_login":"jens arne.hansen","display_name":"Jens Arne Hansen","id":"1234"},{"ID":"683","user_login":"jens christian.le fevre munkgaard","display_name":"Jens Christian le Fevre Munkgaard","id":"683"},{"ID":"226","user_login":"jens erik.michaelsen","display_name":"Jens Erik Michaelsen","id":"226"},{"ID":"257","user_login":"jens hoej.christiansen","display_name":"Jens H\u00f8j Christiansen","id":"257"},{"ID":"495","user_login":"jens johan.littau","display_name":"Jens Johan Littau","id":"495"},{"ID":"232","user_login":"jens mejer.frederiksen","display_name":"Jens Mejer Frederiksen","id":"232"},{"ID":"579","user_login":"jens ottar.hansen","display_name":"Jens Ottar Hansen","id":"579"},{"ID":"575","user_login":"jens overgaard.rasmussen","display_name":"Jens Overgaard Rasmussen","id":"575"},{"ID":"1031","user_login":"jens peter.larsen","display_name":"Jens Peter Larsen","id":"1031"},{"ID":"583","user_login":"jens.baj","display_name":"Jens Baj","id":"583"},{"ID":"506","user_login":"jens.bjerre","display_name":"Jens Bjerre","id":"506"},{"ID":"1164","user_login":"jens.frovin","display_name":"Jens Frovin","id":"1164"},{"ID":"467","user_login":"jens.hilligsoee","display_name":"Jens Hilligs\u00f8e","id":"467"},{"ID":"417","user_login":"jens.jacobsen","display_name":"jens jacobsen","id":"417"},{"ID":"1247","user_login":"jens.jansen","display_name":"Jens Jansen","id":"1247"},{"ID":"1137","user_login":"jens.kirkegaard","display_name":"Jens Kirkegaard","id":"1137"},{"ID":"163","user_login":"jens.kragholm","display_name":"Jens Kragholm","id":"163"},{"ID":"292","user_login":"jens.kristensen","display_name":"Jens Kristensen","id":"292"},{"ID":"315","user_login":"jens.larsen","display_name":"Jens Larsen","id":"315"},{"ID":"1106","user_login":"jens.lillebaek","display_name":"Jens Lilleb\u00e6k","id":"1106"},{"ID":"503","user_login":"jens.lindrup","display_name":"Jens Lindrup","id":"503"},{"ID":"558","user_login":"jens.mollerup","display_name":"Jens Mollerup","id":"558"},{"ID":"103","user_login":"jens.pedersen","display_name":"Jens Pedersen","id":"103"},{"ID":"153","user_login":"jens.pedersen-5760","display_name":"Jens Pedersen","id":"153"},{"ID":"872","user_login":"jens.riber meineche","display_name":"Jens Riber Meineche","id":"872"},{"ID":"642","user_login":"jens.seiersen","display_name":"Jens Seiersen","id":"642"},{"ID":"477","user_login":"jens.terp","display_name":"Jens Terp","id":"477"},{"ID":"194","user_login":"jens.thygesen","display_name":"jens Thygesen","id":"194"},{"ID":"912","user_login":"jens.vejrum","display_name":"Jens Vejrum","id":"912"},{"ID":"674","user_login":"jeppe.andreasen","display_name":"Jeppe Andreasen","id":"674"},{"ID":"507","user_login":"jeppe.carlsen","display_name":"Jeppe Carlsen","id":"507"},{"ID":"206","user_login":"jeppe.carstensen","display_name":"Jeppe Carstensen","id":"206"},{"ID":"734","user_login":"jeppe.rahbek","display_name":"Jeppe Rahbek","id":"734"},{"ID":"235","user_login":"jes.lauesen","display_name":"Jes Lauesen","id":"235"},{"ID":"336","user_login":"jesper.adler","display_name":"Jesper Adler","id":"336"},{"ID":"598","user_login":"jesper.berntsen","display_name":"Jesper Berntsen","id":"598"},{"ID":"497","user_login":"jesper.christensen","display_name":"Jesper Christensen","id":"497"},{"ID":"611","user_login":"jesper.christensen-4817","display_name":"Jesper Christensen","id":"611"},{"ID":"158","user_login":"jesper.hasager","display_name":"Jesper Hasager","id":"158"},{"ID":"662","user_login":"jesper.hausted","display_name":"Jesper Hausted","id":"662"},{"ID":"969","user_login":"jesper.iversen","display_name":"Jesper Iversen","id":"969"},{"ID":"1092","user_login":"jesper.joergensen","display_name":"Jesper J\u00f8rgensen","id":"1092"},{"ID":"1185","user_login":"jesper.kjersgaard","display_name":"Jesper Kjersgaard","id":"1185"},{"ID":"634","user_login":"jesper.kliborg","display_name":"Jesper Kliborg","id":"634"},{"ID":"1151","user_login":"jesper.krag-andersen","display_name":"Jesper Krag-Andersen","id":"1151"},{"ID":"908","user_login":"jesper.kristensen","display_name":"Jesper Kristensen","id":"908"},{"ID":"59","user_login":"jesper.leonardo pedersen","display_name":"Jesper Leonardo Pedersen","id":"59"},{"ID":"834","user_login":"jesper.milthers","display_name":"jesper milthers","id":"834"},{"ID":"472","user_login":"jesper.nygaard","display_name":"Jesper Nygaard","id":"472"},{"ID":"1129","user_login":"jesper.petersen","display_name":"Jesper Petersen","id":"1129"},{"ID":"1261","user_login":"jesper.petersen-4418","display_name":"Jesper Petersen","id":"1261"},{"ID":"797","user_login":"jesper.sandberg","display_name":"Jesper Sandberg","id":"797"},{"ID":"302","user_login":"jesper.vind","display_name":"jesper vind","id":"302"},{"ID":"554","user_login":"jesper.vogt","display_name":"Jesper Vogt","id":"554"},{"ID":"76","user_login":"jess.nielsen","display_name":"Jess Nielsen","id":"76"},{"ID":"746","user_login":"joachim.larsen","display_name":"Joachim Larsen","id":"746"},{"ID":"87","user_login":"joakim.sandroos","display_name":"Joakim Sandroos","id":"87"},{"ID":"373","user_login":"joe.alexandersen","display_name":"Joe Alexandersen","id":"373"},{"ID":"1307","user_login":"joergen.cornett","display_name":"J\u00f8rgen Cornett","id":"1307"},{"ID":"1255","user_login":"joergen.glaesel","display_name":"J\u00f8rgen Gl\u00e6sel","id":"1255"},{"ID":"884","user_login":"joergen.karva","display_name":"J\u00f8rgen Karva","id":"884"},{"ID":"1057","user_login":"joergen.kjaeldgaard","display_name":"j\u00f8rgen kj\u00e6ldgaard","id":"1057"},{"ID":"162","user_login":"joergen.meedom","display_name":"J\u00f8rgen Meedom","id":"162"},{"ID":"347","user_login":"joergen.morsing","display_name":"J\u00f8rgen Morsing","id":"347"},{"ID":"930","user_login":"joergen.raffnsoee","display_name":"J\u00f8rgen Raffns\u00f8e","id":"930"},{"ID":"886","user_login":"joergen.rasmussen","display_name":"J\u00f8rgen Rasmussen","id":"886"},{"ID":"1207","user_login":"joergen.solmer","display_name":"J\u00f8rgen Solmer","id":"1207"},{"ID":"291","user_login":"joergen.sparre","display_name":"JOERGEN SPARRE","id":"291"},{"ID":"250","user_login":"joergen.stoevring","display_name":"J\u00f8rgen St\u00f8vring","id":"250"},{"ID":"365","user_login":"joergensen.martin","display_name":"J\u00f8rgensen Martin","id":"365"},{"ID":"564","user_login":"joern.hoejfeldt","display_name":"J\u00f8rn H\u00f8jfeldt","id":"564"},{"ID":"8","user_login":"joern.sollid","display_name":"J\u00f8rn Sollid","id":"8"},{"ID":"4","user_login":"Johan","display_name":"Johan Christian Sollid","id":"4"},{"ID":"776","user_login":"johan bruun.kreibke","display_name":"Johan Bruun Kreibke","id":"776"},{"ID":"973","user_login":"johan dahlquist.bay-petersen","display_name":"Johan Dahlquist Bay-Petersen","id":"973"},{"ID":"485","user_login":"johan holm.hansen","display_name":"Johan Holm Hansen","id":"485"},{"ID":"274","user_login":"johann.jakobsen","display_name":"Johann jakobsen","id":"274"},{"ID":"264","user_login":"johannes.bak","display_name":"Johannes Bak","id":"264"},{"ID":"1165","user_login":"johannes.kromann bie","display_name":"Johannes Kromann Bie","id":"1165"},{"ID":"593","user_login":"johannes.larsen","display_name":"Johannes Larsen","id":"593"},{"ID":"1220","user_login":"johannes.skotte","display_name":"Johannes Skotte","id":"1220"},{"ID":"1059","user_login":"john.burke-hansen","display_name":"John Burke-Hansen","id":"1059"},{"ID":"984","user_login":"john.christensen","display_name":"John Christensen","id":"984"},{"ID":"547","user_login":"john.christiansen","display_name":"John Christiansen","id":"547"},{"ID":"275","user_login":"john.kitchener","display_name":"John Kitchener","id":"275"},{"ID":"322","user_login":"john.kitchener-4094","display_name":"John Kitchener","id":"322"},{"ID":"560","user_login":"john.soerensen","display_name":"John s\u00f8rensen","id":"560"},{"ID":"88","user_login":"john.steenfeldt-jensen","display_name":"John Steenfeldt-Jensen","id":"88"},{"ID":"1279","user_login":"jon.askjaer joergensen","display_name":"Jon Askj\u00e6r J\u00f8rgensen","id":"1279"},{"ID":"125","user_login":"jon.bendtsen","display_name":"Jon Bendtsen","id":"125"},{"ID":"956","user_login":"jonas.augustenborg","display_name":"Jonas Augustenborg","id":"956"},{"ID":"572","user_login":"jonas.bonnichsen","display_name":"Jonas Bonnichsen","id":"572"},{"ID":"86","user_login":"jonas.bulow knudsen","display_name":"Jonas B\u00fclow Knudsen","id":"86"},{"ID":"196","user_login":"jonas.daugaard","display_name":"Jonas Daugaard","id":"196"},{"ID":"661","user_login":"jonas.kaeseler","display_name":"Jonas K\u00e6seler","id":"661"},{"ID":"874","user_login":"jonas.kortsen","display_name":"Jonas Kortsen","id":"874"},{"ID":"914","user_login":"jonas.laursen","display_name":"Jonas Laursen","id":"914"},{"ID":"589","user_login":"jonas.madsen","display_name":"Jonas Madsen","id":"589"},{"ID":"771","user_login":"jonas.mathiasen","display_name":"Jonas Mathiasen","id":"771"},{"ID":"327","user_login":"jonas.nissen","display_name":"Jonas Nissen","id":"327"},{"ID":"638","user_login":"jonas.nittegaard","display_name":"Jonas Nittegaard","id":"638"},{"ID":"1166","user_login":"jonas.steentoft","display_name":"Jonas Steentoft","id":"1166"},{"ID":"305","user_login":"jonatan eglitis.soerensen","display_name":"Jonatan Eglitis S\u00f8rensen","id":"305"},{"ID":"529","user_login":"jonatan.bording","display_name":"Jonatan Bording","id":"529"},{"ID":"905","user_login":"jonna vejrup.carlsen","display_name":"Jonna Vejrup Carlsen","id":"905"},{"ID":"1158","user_login":"jorgen.borsch","display_name":"J\u00f6rgen B\u00f6rsch","id":"1158"},{"ID":"380","user_login":"joris.bruun-hansen","display_name":"Joris Bruun-Hansen","id":"380"},{"ID":"97","user_login":"JP","display_name":"Jens Peter Dueholm","id":"97"},{"ID":"470","user_login":"julie.torpegaard","display_name":"Julie Torpegaard","id":"470"},{"ID":"1295","user_login":"jurgen.kuhn","display_name":"J\u00fcrgen Kuhn","id":"1295"},{"ID":"500","user_login":"k.w","display_name":"K W","id":"500"},{"ID":"1066","user_login":"kaare sloth.jensen","display_name":"K\u00e5re Sloth Jensen","id":"1066"},{"ID":"768","user_login":"kaare yndgaard.soerensen","display_name":"K\u00e5re Yndgaard S\u00f8rensen","id":"768"},{"ID":"491","user_login":"kahraman.kilic","display_name":"Kahraman Kilic","id":"491"},{"ID":"1105","user_login":"kaj.svenningsen","display_name":"Kaj Svenningsen","id":"1105"},{"ID":"1227","user_login":"kajsa laila.carlsen","display_name":"Kajsa Laila Carlsen","id":"1227"},{"ID":"475","user_login":"kari.havsland","display_name":"Kari Havsland","id":"475"},{"ID":"265","user_login":"karin.toft","display_name":"Karin Toft","id":"265"},{"ID":"23","user_login":"karsten.rasmussen","display_name":"Karsten Rasmussen","id":"23"},{"ID":"633","user_login":"karsten.zakarias","display_name":"Karsten Zakarias","id":"633"},{"ID":"1100","user_login":"kasper trondhjem.moeltov","display_name":"Kasper Trondhjem M\u00f8ltov","id":"1100"},{"ID":"505","user_login":"kasper.andersen","display_name":"Kasper Andersen","id":"505"},{"ID":"360","user_login":"kasper.hansen","display_name":"Kasper Hansen","id":"360"},{"ID":"669","user_login":"kasper.hareskov tygesen","display_name":"Kasper Hareskov Tygesen","id":"669"},{"ID":"1146","user_login":"kasper.johansen","display_name":"Kasper Johansen","id":"1146"},{"ID":"1028","user_login":"kasper.larsen","display_name":"Kasper Larsen","id":"1028"},{"ID":"1103","user_login":"kasper.laustsen","display_name":"Kasper Laustsen","id":"1103"},{"ID":"835","user_login":"kasper.nielsen","display_name":"Kasper Nielsen","id":"835"},{"ID":"881","user_login":"kasper.pihl","display_name":"Kasper Pihl","id":"881"},{"ID":"104","user_login":"kasper.rosenberg","display_name":"Kasper Rosenberg","id":"104"},{"ID":"1169","user_login":"kasper.sandbaek frederiksen","display_name":"Kasper Sandb\u00e6k Frederiksen","id":"1169"},{"ID":"19","user_login":"kasper.skov","display_name":"Kasper Skov","id":"19"},{"ID":"614","user_login":"kasper.sommer","display_name":"Kasper Sommer","id":"614"},{"ID":"807","user_login":"kasper.stoltze","display_name":"Kasper Stoltze","id":"807"},{"ID":"294","user_login":"kasper.teilmann","display_name":"Kasper Teilmann","id":"294"},{"ID":"368","user_login":"kathrine.eduard","display_name":"Kathrine Eduard","id":"368"},{"ID":"853","user_login":"katrine.daugaard","display_name":"Katrine Daugaard","id":"853"},{"ID":"407","user_login":"keld marstrand.wang","display_name":"Keld Marstrand Wang","id":"407"},{"ID":"707","user_login":"keld.kristensen","display_name":"Keld Kristensen","id":"707"},{"ID":"742","user_login":"keld.poulsen","display_name":"Keld Poulsen","id":"742"},{"ID":"1072","user_login":"kenneth lund.holm","display_name":"Kenneth Lund Holm","id":"1072"},{"ID":"622","user_login":"kenneth.kristoffersen","display_name":"Kenneth Kristoffersen","id":"622"},{"ID":"775","user_login":"kenneth.langstrup","display_name":"Kenneth Langstrup","id":"775"},{"ID":"421","user_login":"kenneth.lauritsen","display_name":"Kenneth Lauritsen","id":"421"},{"ID":"136","user_login":"kenneth.nielsen","display_name":"Kenneth Nielsen","id":"136"},{"ID":"342","user_login":"kenneth.skatka hammer","display_name":"Kenneth Skatka Hammer","id":"342"},{"ID":"251","user_login":"kenneth.thomsen","display_name":"Kenneth Thomsen","id":"251"},{"ID":"608","user_login":"kenni.madsen","display_name":"Kenni Madsen","id":"608"},{"ID":"762","user_login":"kenny.munck","display_name":"Kenny Munck","id":"762"},{"ID":"1198","user_login":"kenny.simmelsgaard","display_name":"Kenny Simmelsgaard","id":"1198"},{"ID":"605","user_login":"kevin.hagemann petersen","display_name":"Kevin Hagemann Petersen","id":"605"},{"ID":"1009","user_login":"kevin.soelvhoej","display_name":"Kevin S\u00f8lvh\u00f8j","id":"1009"},{"ID":"382","user_login":"kia.vedel","display_name":"Kia Vedel","id":"382"},{"ID":"714","user_login":"kim elbaek.petersen","display_name":"Kim Elb\u00e6k Petersen","id":"714"},{"ID":"362","user_login":"kim verhein.hoffmann","display_name":"Kim Verhein Hoffmann","id":"362"},{"ID":"631","user_login":"kim.biel-nielsen","display_name":"Kim Biel-Nielsen","id":"631"},{"ID":"988","user_login":"kim.bjoernstrup","display_name":"kim Bj\u00f8rnstrup","id":"988"},{"ID":"1101","user_login":"kim.eriksen","display_name":"Kim Eriksen","id":"1101"},{"ID":"444","user_login":"kim.hartvigsen","display_name":"Kim Hartvigsen","id":"444"},{"ID":"525","user_login":"kim.helsinghoff","display_name":"Kim Helsinghoff","id":"525"},{"ID":"237","user_login":"kim.jensen","display_name":"Kim Jensen","id":"237"},{"ID":"937","user_login":"kim.rasmussen","display_name":"Kim Rasmussen","id":"937"},{"ID":"1104","user_login":"kim.scheel","display_name":"Kim Scheel","id":"1104"},{"ID":"663","user_login":"kim.soerensen","display_name":"Kim S\u00f8rensen","id":"663"},{"ID":"1176","user_login":"kim.toftum","display_name":"Kim Toftum","id":"1176"},{"ID":"1030","user_login":"kirsten.soerensen","display_name":"Kirsten S\u00f8rensen","id":"1030"},{"ID":"1296","user_login":"kit louise.strand","display_name":"Kit Louise Strand","id":"1296"},{"ID":"392","user_login":"kjeld.abel","display_name":"Kjeld Abel","id":"392"},{"ID":"438","user_login":"kjeld.nielsen","display_name":"Kjeld Nielsen","id":"438"},{"ID":"980","user_login":"klaus bjoern.jensen","display_name":"Klaus Bj\u00f8rn Jensen","id":"980"},{"ID":"1050","user_login":"klaus ferslev.jensen","display_name":"Klaus Ferslev Jensen","id":"1050"},{"ID":"75","user_login":"klaus thorsen.sieg","display_name":"Klaus Thorsen Sieg","id":"75"},{"ID":"1240","user_login":"klaus.billund","display_name":"Klaus Billund","id":"1240"},{"ID":"242","user_login":"klaus.falk","display_name":"Klaus Falk","id":"242"},{"ID":"69","user_login":"klaus.moeldrup","display_name":"Klaus M\u00f8ldrup","id":"69"},{"ID":"723","user_login":"klaus.stoeve","display_name":"Klaus St\u00f8ve","id":"723"},{"ID":"936","user_login":"klaus.thuesen","display_name":"Klaus Thuesen","id":"936"},{"ID":"1230","user_login":"knud.back","display_name":"Knud Back","id":"1230"},{"ID":"915","user_login":"knud.hammer","display_name":"Knud Hammer","id":"915"},{"ID":"1084","user_login":"knud.knudsen","display_name":"Knud Knudsen","id":"1084"},{"ID":"77","user_login":"knud.rasmussen","display_name":"Knud Rasmussen","id":"77"},{"ID":"949","user_login":"kresten.bertelsrn","display_name":"Kresten Bertelsrn","id":"949"},{"ID":"828","user_login":"kresten.mikkelsen","display_name":"Kresten Mikkelsen","id":"828"},{"ID":"684","user_login":"kresten.soerensen","display_name":"Kresten S\u00f8rensen","id":"684"},{"ID":"1202","user_login":"kris.walther","display_name":"Kris Walther","id":"1202"},{"ID":"1070","user_login":"krister.noergaard","display_name":"Krister N\u00f8rgaard","id":"1070"},{"ID":"1186","user_login":"kristian israelsen.olsen","display_name":"Kristian Israelsen Olsen","id":"1186"},{"ID":"263","user_login":"kristian.balle","display_name":"Kristian Balle","id":"263"},{"ID":"385","user_login":"kristian.broendum","display_name":"Kristian Br\u00f8ndum","id":"385"},{"ID":"1004","user_login":"kristian.hermind johansen","display_name":"Kristian Hermind Johansen","id":"1004"},{"ID":"1062","user_login":"kristian.horslund","display_name":"Kristian Horslund","id":"1062"},{"ID":"15","user_login":"kristian.jakobsen","display_name":"Kristian Jakobsen","id":"15"},{"ID":"704","user_login":"kristian.kahle","display_name":"Kristian Kahle","id":"704"},{"ID":"830","user_login":"kristian.klim","display_name":"Kristian Klim","id":"830"},{"ID":"494","user_login":"kristian.korsgaard","display_name":"Kristian Korsgaard","id":"494"},{"ID":"809","user_login":"kristian.krogh","display_name":"Kristian Krogh","id":"809"},{"ID":"1049","user_login":"kristian.laursen","display_name":"Kristian Laursen","id":"1049"},{"ID":"916","user_login":"kristian.soerensen","display_name":"Kristian S\u00f8rensen","id":"916"},{"ID":"321","user_login":"kristine.gazel","display_name":"Kristine Gazel","id":"321"},{"ID":"716","user_login":"kristjan.baldursson","display_name":"Kristjan Baldursson","id":"716"},{"ID":"160","user_login":"kurt.lauridsen","display_name":"Kurt Lauridsen","id":"160"},{"ID":"1081","user_login":"lars bo.thomsen","display_name":"Lars Bo Thomsen","id":"1081"},{"ID":"312","user_login":"lars boje soenderby.jensen","display_name":"Lars Boje S\u00f8nderby Jensen","id":"312"},{"ID":"157","user_login":"lars christian ungstrup.nielsen","display_name":"Lars Christian Ungstrup Nielsen","id":"157"},{"ID":"223","user_login":"lars christian.nielsen","display_name":"Lars Christian Nielsen","id":"223"},{"ID":"335","user_login":"lars henrik.ley","display_name":"Lars Henrik Ley","id":"335"},{"ID":"1262","user_login":"lars roland.andersen","display_name":"Lars Roland Andersen","id":"1262"},{"ID":"328","user_login":"lars.astrup","display_name":"Lars Astrup","id":"328"},{"ID":"448","user_login":"lars.bruhn","display_name":"Lars Bruhn","id":"448"},{"ID":"689","user_login":"lars.djernaes","display_name":"Lars Djernaes","id":"689"},{"ID":"658","user_login":"lars.gotlieb","display_name":"Lars Gotlieb","id":"658"},{"ID":"812","user_login":"lars.hansen","display_name":"Lars Hansen","id":"812"},{"ID":"1167","user_login":"lars.jensen","display_name":"Lars Jensen","id":"1167"},{"ID":"1108","user_login":"lars.kiemer","display_name":"Lars Kiemer","id":"1108"},{"ID":"1267","user_login":"lars.kristiansen","display_name":"Lars Kristiansen","id":"1267"},{"ID":"571","user_login":"lars.madsen","display_name":"lars madsen","id":"571"},{"ID":"816","user_login":"lars.murer","display_name":"Lars M\u00fcrer","id":"816"},{"ID":"288","user_login":"lars.nielsen","display_name":"Lars Nielsen","id":"288"},{"ID":"696","user_login":"lars.nielsen-7837","display_name":"Lars Nielsen","id":"696"},{"ID":"205","user_login":"lars.pedersen","display_name":"Lars Pedersen","id":"205"},{"ID":"219","user_login":"lars.rise","display_name":"Lars Rise","id":"219"},{"ID":"1079","user_login":"lars.sloth","display_name":"Lars Sloth","id":"1079"},{"ID":"210","user_login":"lars.truelsen","display_name":"Lars Truelsen","id":"210"},{"ID":"195","user_login":"lars.viggers","display_name":"Lars Viggers","id":"195"},{"ID":"1124","user_login":"lasse.bjerre","display_name":"Lasse Bjerre","id":"1124"},{"ID":"719","user_login":"lasse.boa","display_name":"Lasse Boa","id":"719"},{"ID":"644","user_login":"lasse.brunoe","display_name":"Lasse Brun\u00f8","id":"644"},{"ID":"736","user_login":"lasse.dahlerup","display_name":"Lasse Dahlerup","id":"736"},{"ID":"306","user_login":"lasse.hoegstedt","display_name":"Lasse H\u00f8gstedt","id":"306"},{"ID":"695","user_login":"lasse.iversen","display_name":"Lasse Iversen","id":"695"},{"ID":"33","user_login":"lasse.joergensen","display_name":"Lasse J\u00f8rgensen","id":"33"},{"ID":"961","user_login":"lasse.kammer","display_name":"Lasse Kammer","id":"961"},{"ID":"281","user_login":"lasse.lourenco","display_name":"Lasse Lourenco","id":"281"},{"ID":"787","user_login":"lasse.mandal","display_name":"Lasse Mandal","id":"787"},{"ID":"963","user_login":"lasse.penning","display_name":"Lasse Penning","id":"963"},{"ID":"693","user_login":"lasse.philipsen","display_name":"Lasse Philipsen","id":"693"},{"ID":"1110","user_login":"lasse.rasmussen","display_name":"Lasse Rasmussen","id":"1110"},{"ID":"1272","user_login":"lasse.vesterled","display_name":"Lasse Vesterled","id":"1272"},{"ID":"146","user_login":"lasse.wagner","display_name":"Lasse Wagner","id":"146"},{"ID":"1056","user_login":"lauge.feierskov","display_name":"Lauge Feierskov","id":"1056"},{"ID":"213","user_login":"laurens.moss","display_name":"Laurens Moss","id":"213"},{"ID":"105","user_login":"laurits.riis lund","display_name":"Laurits Riis Lund","id":"105"},{"ID":"1277","user_login":"laust.kildevaeld","display_name":"laust kildev\u00e6ld","id":"1277"},{"ID":"404","user_login":"laust.soendergaard","display_name":"Laust S\u00f8ndergaard","id":"404"},{"ID":"343","user_login":"laust.vestergaard","display_name":"Laust Vestergaard","id":"343"},{"ID":"1300","user_login":"lean.milo","display_name":"Lean Milo","id":"1300"},{"ID":"464","user_login":"leif hartz.hagensen","display_name":"Leif Hartz Hagensen","id":"464"},{"ID":"209","user_login":"leif steen.pedersen","display_name":"Leif Steen Pedersen","id":"209"},{"ID":"1221","user_login":"leif.jepsen","display_name":"Leif Jepsen","id":"1221"},{"ID":"1241","user_login":"leif.larsen","display_name":"Leif Larsen","id":"1241"},{"ID":"457","user_login":"lene.berg","display_name":"lene berg","id":"457"},{"ID":"357","user_login":"lene.foged","display_name":"Lene Foged","id":"357"},{"ID":"878","user_login":"lene.rasmussen","display_name":"Lene Rasmussen","id":"878"},{"ID":"371","user_login":"lennart.garbarsch","display_name":"Lennart Garbarsch","id":"371"},{"ID":"426","user_login":"lianne.hansen","display_name":"Lianne Hansen","id":"426"},{"ID":"1139","user_login":"lili laerke.nordstroem","display_name":"Lili L\u00e6rke Nordstr\u00f8m","id":"1139"},{"ID":"220","user_login":"lise.dueholm","display_name":"Lise Dueholm","id":"220"},{"ID":"496","user_login":"louise.fazlagic","display_name":"Louise Fazlagic","id":"496"},{"ID":"1210","user_login":"louise.fazlagic-7156","display_name":"Louise Fazlagic","id":"1210"},{"ID":"170","user_login":"lucas.damgaard","display_name":"Lucas Damgaard","id":"170"},{"ID":"489","user_login":"lucas.neve sonne","display_name":"Lucas Neve Sonne","id":"489"},{"ID":"1269","user_login":"luis.kristensen","display_name":"Luis Kristensen","id":"1269"},{"ID":"1061","user_login":"lukas.bakke","display_name":"Lukas Bakke","id":"1061"},{"ID":"6","user_login":"Mads Bunch Larsen","display_name":"Mads Larsen","id":"6"},{"ID":"794","user_login":"mads peter.steenstrup","display_name":"Mads Peter Steenstrup","id":"794"},{"ID":"383","user_login":"mads varming.fonnesbo","display_name":"Mads Varming Fonnesbo","id":"383"},{"ID":"137","user_login":"mads.andersen","display_name":"Mads Andersen","id":"137"},{"ID":"549","user_login":"mads.enevoldsen","display_name":"Mads Enevoldsen","id":"549"},{"ID":"569","user_login":"mads.jansen","display_name":"Mads Jansen","id":"569"},{"ID":"1223","user_login":"mads.joensen","display_name":"Mads Joensen","id":"1223"},{"ID":"377","user_login":"mads.kristensen","display_name":"Mads Kristensen","id":"377"},{"ID":"81","user_login":"mads.larsen","display_name":"Mads Larsen","id":"81"},{"ID":"118","user_login":"mads.larsen-3519","display_name":"Mads Larsen","id":"118"},{"ID":"896","user_login":"mads.lynge","display_name":"Mads Lynge","id":"896"},{"ID":"17","user_login":"mads.pihlman","display_name":"Mads Pihlman","id":"17"},{"ID":"1219","user_login":"mads.ramsing","display_name":"Mads Ramsing","id":"1219"},{"ID":"236","user_login":"mads.sengewald","display_name":"Mads Sengewald","id":"236"},{"ID":"482","user_login":"mads.swensson","display_name":"Mads Swensson","id":"482"},{"ID":"970","user_login":"mads.thomsen","display_name":"Mads Thomsen","id":"970"},{"ID":"643","user_login":"magnus zwicky.burkal","display_name":"Magnus Zwicky Burkal","id":"643"},{"ID":"273","user_login":"magnus.ahler","display_name":"Magnus Ahler","id":"273"},{"ID":"100","user_login":"magnus.andersen","display_name":"Magnus Andersen","id":"100"},{"ID":"479","user_login":"magnus.cort","display_name":"Magnus Cort","id":"479"},{"ID":"418","user_login":"magnus.nilsen","display_name":"Magnus Nilsen","id":"418"},{"ID":"861","user_login":"magnus.vesth","display_name":"Magnus Vesth","id":"861"},{"ID":"1107","user_login":"malene.byskov","display_name":"Malene Byskov","id":"1107"},{"ID":"1195","user_login":"malene.flagga","display_name":"Malene Flagga","id":"1195"},{"ID":"504","user_login":"malte.bock","display_name":"Malte Bock","id":"504"},{"ID":"891","user_login":"malthe steffen.pedersen","display_name":"Malthe Steffen Pedersen","id":"891"},{"ID":"1275","user_login":"manette.klaning","display_name":"Manette Kl\u00e4ning","id":"1275"},{"ID":"428","user_login":"marc.dose","display_name":"Marc Dose","id":"428"},{"ID":"429","user_login":"marc.jeppesen","display_name":"Marc Jeppesen","id":"429"},{"ID":"390","user_login":"marc.ziebe","display_name":"Marc Ziebe","id":"390"},{"ID":"425","user_login":"marco.lund","display_name":"Marco Lund","id":"425"},{"ID":"1182","user_login":"marcus.ernoe-heising","display_name":"Marcus Ern\u00f8-Heising","id":"1182"},{"ID":"1054","user_login":"maria.vorbeck","display_name":"maria Vorbeck","id":"1054"},{"ID":"817","user_login":"marianne noerskov.adrian","display_name":"Marianne N\u00f8rskov Adrian","id":"817"},{"ID":"1172","user_login":"marianne tanghus.kristensen","display_name":"Marianne Tanghus Kristensen","id":"1172"},{"ID":"680","user_login":"marianne.nielsen","display_name":"Marianne Nielsen","id":"680"},{"ID":"1216","user_login":"marie louise.freiberg","display_name":"Marie Louise Freiberg","id":"1216"},{"ID":"1134","user_login":"marie.breiner","display_name":"Marie Breiner","id":"1134"},{"ID":"1184","user_login":"marie.noes","display_name":"Marie Noes","id":"1184"},{"ID":"26","user_login":"marius boess.soerensen","display_name":"Marius B\u00f8ss S\u00f8rensen","id":"26"},{"ID":"1075","user_login":"marius leander.jensen","display_name":"Marius Leander Jensen","id":"1075"},{"ID":"154","user_login":"marius.aaen","display_name":"Marius Aaen","id":"154"},{"ID":"80","user_login":"marius.helmer larsen","display_name":"Marius Helmer Larsen","id":"80"},{"ID":"308","user_login":"mark.korsgaard fenger","display_name":"Mark Korsgaard Fenger","id":"308"},{"ID":"577","user_login":"mark.lajer","display_name":"Mark Lajer","id":"577"},{"ID":"1159","user_login":"mark.nathansen","display_name":"Mark Nathansen","id":"1159"},{"ID":"441","user_login":"mark.nielsen","display_name":"Mark Nielsen","id":"441"},{"ID":"156","user_login":"martin haarup.pedersen","display_name":"Martin Haarup Pedersen","id":"156"},{"ID":"620","user_login":"martin jason.adelgaard","display_name":"Martin Jason Adelgaard","id":"620"},{"ID":"610","user_login":"martin rejkjaer.abildgaard","display_name":"Martin Rejkj\u00e6r Abildgaard","id":"610"},{"ID":"718","user_login":"martin.baunsgaard","display_name":"Martin Baunsgaard","id":"718"},{"ID":"887","user_login":"martin.boetkjaer","display_name":"Martin B\u00f8tkj\u00e6r","id":"887"},{"ID":"747","user_login":"martin.broellund","display_name":"Martin Br\u00f8llund","id":"747"},{"ID":"350","user_login":"martin.christiansen","display_name":"Martin Christiansen","id":"350"},{"ID":"767","user_login":"martin.faber","display_name":"Martin Faber","id":"767"},{"ID":"184","user_login":"martin.foenlev nicolajsen","display_name":"Martin F\u00f8nlev Nicolajsen","id":"184"},{"ID":"159","user_login":"martin.fuks","display_name":"Martin Fuks","id":"159"},{"ID":"758","user_login":"martin.hansen","display_name":"Martin Hansen","id":"758"},{"ID":"790","user_login":"martin.harss","display_name":"Martin Harss","id":"790"},{"ID":"947","user_login":"martin.helms","display_name":"Martin Helms","id":"947"},{"ID":"1021","user_login":"martin.hilligsoee","display_name":"Martin Hilligs\u00f8e","id":"1021"},{"ID":"1288","user_login":"martin.holm-petersen","display_name":"Martin Holm-Petersen","id":"1288"},{"ID":"361","user_login":"martin.klitgaard","display_name":"Martin Klitgaard","id":"361"},{"ID":"53","user_login":"martin.lund","display_name":"Martin Lund","id":"53"},{"ID":"731","user_login":"martin.moelgaard","display_name":"Martin M\u00f8lgaard","id":"731"},{"ID":"673","user_login":"martin.petersen","display_name":"Martin Petersen","id":"673"},{"ID":"664","user_login":"martin.rasmussen","display_name":"Martin Rasmussen","id":"664"},{"ID":"286","user_login":"martin.rauschenberg bregendahl","display_name":"Martin Rauschenberg Bregendahl","id":"286"},{"ID":"848","user_login":"martin.rex","display_name":"Martin Rex","id":"848"},{"ID":"645","user_login":"martin.rye-konig","display_name":"Martin Rye-K\u00f6nig","id":"645"},{"ID":"688","user_login":"martin.schmidt","display_name":"Martin Schmidt","id":"688"},{"ID":"946","user_login":"martin.simonsen","display_name":"martin simonsen","id":"946"},{"ID":"1217","user_login":"martin.stene","display_name":"Martin Stene","id":"1217"},{"ID":"1308","user_login":"martin.thomsen","display_name":"Martin Thomsen","id":"1308"},{"ID":"198","user_login":"martin.tranders","display_name":"Martin Tranders","id":"198"},{"ID":"923","user_login":"martin.ville","display_name":"Martin Ville","id":"923"},{"ID":"756","user_login":"martin.werlin munk","display_name":"Martin Werlin Munk","id":"756"},{"ID":"632","user_login":"martina.h. andersen","display_name":"Martina H. Andersen","id":"632"},{"ID":"1102","user_login":"mathias emil.kaae","display_name":"Mathias Emil Kaae","id":"1102"},{"ID":"962","user_login":"mathias.berglund mathiesen","display_name":"Mathias Berglund Mathiesen","id":"962"},{"ID":"446","user_login":"mathias.byskov","display_name":"Mathias Byskov","id":"446"},{"ID":"443","user_login":"mathias.holdrup","display_name":"Mathias Holdrup","id":"443"},{"ID":"879","user_login":"mathias.iversen","display_name":"Mathias Iversen","id":"879"},{"ID":"1249","user_login":"mathias.madsen","display_name":"Mathias Madsen","id":"1249"},{"ID":"679","user_login":"mathias.noerregaard","display_name":"Mathias N\u00f8rregaard","id":"679"},{"ID":"414","user_login":"mathias.raahauge","display_name":"Mathias Raahauge","id":"414"},{"ID":"207","user_login":"mathias.skovsboel","display_name":"Mathias Skovsboel","id":"207"},{"ID":"1121","user_login":"mathias.zilstorff","display_name":"Mathias Zilstorff","id":"1121"},{"ID":"883","user_login":"mathies.henriksen","display_name":"Mathies Henriksen","id":"883"},{"ID":"94","user_login":"mathis.aguero-noerrelykke","display_name":"Mathis Ag\u00fcero-N\u00f8rrelykke","id":"94"},{"ID":"378","user_login":"max.mortensen","display_name":"Max Mortensen","id":"378"},{"ID":"1005","user_login":"max.quorning","display_name":"Max Quorning","id":"1005"},{"ID":"131","user_login":"mette.lindholm","display_name":"Mette Lindholm","id":"131"},{"ID":"934","user_login":"michael faust.horsboell","display_name":"Michael Faust Horsb\u00f8ll","id":"934"},{"ID":"188","user_login":"michael juul.hansen","display_name":"Michael Juul Hansen","id":"188"},{"ID":"1111","user_login":"michael.andersen","display_name":"Michael Andersen","id":"1111"},{"ID":"358","user_login":"michael.bisfelt","display_name":"Michael Bisfelt","id":"358"},{"ID":"635","user_login":"michael.christensen","display_name":"Michael Christensen","id":"635"},{"ID":"850","user_login":"michael.claville","display_name":"Michael Claville","id":"850"},{"ID":"348","user_login":"michael.frommelt","display_name":"Michael Frommelt","id":"348"},{"ID":"1171","user_login":"michael.haugaard","display_name":"Michael Haugaard","id":"1171"},{"ID":"966","user_login":"michael.hye","display_name":"Michael Hye","id":"966"},{"ID":"1292","user_login":"michael.jensen","display_name":"Michael Jensen","id":"1292"},{"ID":"499","user_login":"michael.keldsen","display_name":"Michael Keldsen","id":"499"},{"ID":"933","user_login":"michael.knoblauch","display_name":"Michael Knoblauch","id":"933"},{"ID":"527","user_login":"michael.knudsen","display_name":"Michael Knudsen","id":"527"},{"ID":"247","user_login":"michael.larsen","display_name":"Michael larsen","id":"247"},{"ID":"1306","user_login":"michael.madsen","display_name":"Michael Madsen","id":"1306"},{"ID":"311","user_login":"michael.munk","display_name":"Michael Munk","id":"311"},{"ID":"1017","user_login":"michael.rasmussen","display_name":"Michael Rasmussen","id":"1017"},{"ID":"665","user_login":"michael.soendergaard","display_name":"Michael S\u00f8ndergaard","id":"665"},{"ID":"1091","user_login":"michael.soerensen","display_name":"Michael S\u00f8rensen","id":"1091"},{"ID":"453","user_login":"michael.stahl","display_name":"Michael Stahl","id":"453"},{"ID":"823","user_login":"michael.vejlstrup","display_name":"Michael Vejlstrup","id":"823"},{"ID":"1093","user_login":"michel.poulsen","display_name":"Michel Poulsen","id":"1093"},{"ID":"298","user_login":"michel.thrysoee","display_name":"Michel Thrys\u00f8e","id":"298"},{"ID":"129","user_login":"mika.larsen","display_name":"Mika Larsen","id":"129"},{"ID":"1237","user_login":"mikael.estrup","display_name":"mikael estrup","id":"1237"},{"ID":"366","user_login":"mike.christiansen","display_name":"Mike Christiansen","id":"366"},{"ID":"702","user_login":"mikkel grejsmark.mogensen","display_name":"Mikkel Grejsmark Mogensen","id":"702"},{"ID":"229","user_login":"mikkel.balslev","display_name":"Mikkel Balslev","id":"229"},{"ID":"341","user_login":"mikkel.blaabjerg","display_name":"Mikkel Blaabjerg","id":"341"},{"ID":"586","user_login":"mikkel.dam","display_name":"Mikkel Dam","id":"586"},{"ID":"277","user_login":"mikkel.ejsing","display_name":"Mikkel Ejsing","id":"277"},{"ID":"384","user_login":"mikkel.froejk","display_name":"Mikkel Fr\u00f8jk","id":"384"},{"ID":"667","user_login":"mikkel.johnsen","display_name":"Mikkel Johnsen","id":"667"},{"ID":"1266","user_login":"mikkel.jungshoved","display_name":"Mikkel Jungshoved","id":"1266"},{"ID":"894","user_login":"mikkel.moeller","display_name":"Mikkel M\u00f8ller","id":"894"},{"ID":"862","user_login":"mikkel.pedersen","display_name":"Mikkel Pedersen","id":"862"},{"ID":"337","user_login":"mikkel.rugholm","display_name":"Mikkel Rugholm","id":"337"},{"ID":"967","user_login":"mikkel.soerensen","display_name":"Mikkel S\u00f8rensen","id":"967"},{"ID":"1215","user_login":"mirja.soender gjaldbaek","display_name":"Mirja S\u00f8nder Gjaldb\u00e6k","id":"1215"},{"ID":"96","user_login":"mogens boejstrup.nielsen","display_name":"Mogens B\u00f8jstrup Nielsen","id":"96"},{"ID":"323","user_login":"mogens dam.petersen","display_name":"Mogens Dam Petersen","id":"323"},{"ID":"880","user_login":"mogens.jacobsen","display_name":"Mogens Jacobsen","id":"880"},{"ID":"888","user_login":"mogens.matthiesen","display_name":"Mogens Matthiesen","id":"888"},{"ID":"1013","user_login":"mogens.vestergaard","display_name":"Mogens Vestergaard","id":"1013"},{"ID":"356","user_login":"mortan.martinsson","display_name":"Mortan Martinsson","id":"356"},{"ID":"150","user_login":"morten bo.kristensen","display_name":"Morten Bo Kristensen","id":"150"},{"ID":"405","user_login":"morten dahlgren.jensen","display_name":"Morten Dahlgren Jensen","id":"405"},{"ID":"1131","user_login":"morten emil jeppesen.bernstein","display_name":"Morten Emil Jeppesen Bernstein","id":"1131"},{"ID":"178","user_login":"morten holm.steinbeck","display_name":"Morten Holm Steinbeck","id":"178"},{"ID":"526","user_login":"morten moeller.riis","display_name":"Morten M\u00f8ller Riis","id":"526"},{"ID":"433","user_login":"morten moerck.rugholm","display_name":"Morten M\u00f8rck Rugholm","id":"433"},{"ID":"1257","user_login":"morten.bruun","display_name":"Morten Bruun","id":"1257"},{"ID":"411","user_login":"morten.dam","display_name":"Morten Dam","id":"411"},{"ID":"152","user_login":"morten.eriksen","display_name":"Morten Eriksen","id":"152"},{"ID":"1003","user_login":"morten.falk","display_name":"Morten Falk","id":"1003"},{"ID":"43","user_login":"morten.fog","display_name":"Morten Fog","id":"43"},{"ID":"21","user_login":"morten.jakobsen","display_name":"Morten Jakobsen","id":"21"},{"ID":"1019","user_login":"morten.jensen","display_name":"Morten Jensen","id":"1019"},{"ID":"706","user_login":"morten.joergensen","display_name":"Morten J\u00f8rgensen","id":"706"},{"ID":"979","user_login":"morten.klint","display_name":"Morten Klint","id":"979"},{"ID":"578","user_login":"morten.kryger","display_name":"Morten Kryger","id":"578"},{"ID":"672","user_login":"morten.larsen","display_name":"Morten Larsen","id":"672"},{"ID":"938","user_login":"morten.leth","display_name":"Morten Leth","id":"938"},{"ID":"394","user_login":"morten.lundberg","display_name":"Morten Lundberg","id":"394"},{"ID":"376","user_login":"morten.madsen","display_name":"Morten Madsen","id":"376"},{"ID":"650","user_login":"morten.moeller","display_name":"Morten M\u00f8ller","id":"650"},{"ID":"346","user_login":"morten.morten","display_name":"morten morten","id":"346"},{"ID":"744","user_login":"morten.nielsen","display_name":"Morten Nielsen","id":"744"},{"ID":"280","user_login":"morten.nygaard","display_name":"Morten Nygaard","id":"280"},{"ID":"757","user_login":"morten.paaske","display_name":"Morten Paaske","id":"757"},{"ID":"1144","user_login":"morten.petersen","display_name":"Morten Petersen","id":"1144"},{"ID":"12","user_login":"morten.petz","display_name":"Morten Petz","id":"12"},{"ID":"811","user_login":"morten.scheelsbeck","display_name":"Morten Scheelsbeck","id":"811"},{"ID":"119","user_login":"morten.thing","display_name":"Morten Thing","id":"119"},{"ID":"998","user_login":"morten.trillingsgaard","display_name":"Morten Trillingsgaard","id":"998"},{"ID":"1118","user_login":"morten.wintherlich","display_name":"Morten Wintherlich","id":"1118"},{"ID":"1301","user_login":"Mortenny","display_name":"Mortenny gaard","id":"1301"},{"ID":"1302","user_login":"Mousten","display_name":"S\u00f8ren Mousten","id":"1302"},{"ID":"1304","user_login":"nada","display_name":"nada","id":"1304"},{"ID":"1006","user_login":"neergaard-madsen.uffe","display_name":"neergaard-madsen Uffe","id":"1006"},{"ID":"1245","user_login":"neilsean.victorino","display_name":"Neilsean Victorino","id":"1245"},{"ID":"860","user_login":"nicki.hansen","display_name":"Nicki Hansen","id":"860"},{"ID":"1250","user_login":"nicki.lund","display_name":"Nicki Lund","id":"1250"},{"ID":"733","user_login":"niclas.hornum","display_name":"Niclas Hornum","id":"733"},{"ID":"678","user_login":"nicolai.jensen","display_name":"Nicolai Jensen","id":"678"},{"ID":"37","user_login":"nicolai.mifsud","display_name":"Nicolai Mifsud","id":"37"},{"ID":"935","user_login":"nicolai.oksen","display_name":"Nicolai Oksen","id":"935"},{"ID":"748","user_login":"nicolaj.aaroee","display_name":"Nicolaj Aar\u00f8e","id":"748"},{"ID":"846","user_login":"nicolaj.rasmussen","display_name":"Nicolaj Rasmussen","id":"846"},{"ID":"960","user_login":"niels christian.andersen","display_name":"Niels Christian Andersen","id":"960"},{"ID":"652","user_login":"niels christian.nielsen","display_name":"Niels Christian Nielsen","id":"652"},{"ID":"512","user_login":"niels ejner.hovmoeller","display_name":"Niels Ejner Hovm\u00f8ller","id":"512"},{"ID":"101","user_login":"Niels Momsen","display_name":"Niels Momsen","id":"101"},{"ID":"478","user_login":"niels ole.jacobsen","display_name":"Niels Ole Jacobsen","id":"478"},{"ID":"437","user_login":"niels peter.dahl","display_name":"Niels Peter Dahl","id":"437"},{"ID":"641","user_login":"niels pihl.lorentzen","display_name":"Niels Pihl Lorentzen","id":"641"},{"ID":"841","user_login":"niels platz.bertelsen","display_name":"Niels Platz Bertelsen","id":"841"},{"ID":"531","user_login":"niels vejrup.carlsen","display_name":"Niels Vejrup Carlsen","id":"531"},{"ID":"831","user_login":"niels vestergaard.jespersen","display_name":"Niels Vestergaard Jespersen","id":"831"},{"ID":"927","user_login":"niels-ole.buttrup","display_name":"Niels-Ole Buttrup","id":"927"},{"ID":"72","user_login":"niels.andreasen","display_name":"Niels Andreasen","id":"72"},{"ID":"720","user_login":"niels.broechner","display_name":"Niels Br\u00f8chner","id":"720"},{"ID":"1162","user_login":"niels.bruun de neergaard","display_name":"Niels Bruun de Neergaard","id":"1162"},{"ID":"1122","user_login":"niels.clausen","display_name":"Niels Clausen","id":"1122"},{"ID":"498","user_login":"niels.colding","display_name":"Niels Colding","id":"498"},{"ID":"363","user_login":"niels.ipsen","display_name":"Niels Ipsen","id":"363"},{"ID":"217","user_login":"niels.jensen","display_name":"Niels Jensen","id":"217"},{"ID":"1112","user_login":"niels.josefsen","display_name":"Niels josefsen","id":"1112"},{"ID":"829","user_login":"niels.michaelsen","display_name":"Niels Michaelsen","id":"829"},{"ID":"533","user_login":"niels.oertenblad","display_name":"Niels \u00d8rtenblad","id":"533"},{"ID":"300","user_login":"niels.roenhede","display_name":"Niels R\u00f8nhede","id":"300"},{"ID":"1192","user_login":"nikita.shilenok","display_name":"Nikita Shilenok","id":"1192"},{"ID":"1263","user_login":"nikolai.larsen","display_name":"Nikolai Larsen","id":"1263"},{"ID":"892","user_login":"nikolaj jung.pedersen","display_name":"Nikolaj Jung Pedersen","id":"892"},{"ID":"727","user_login":"nikolaj richter.larsen","display_name":"Nikolaj Richter Larsen","id":"727"},{"ID":"403","user_login":"nikolaj.benjaminsen","display_name":"Nikolaj Benjaminsen","id":"403"},{"ID":"778","user_login":"nikolaj.boeggild","display_name":"Nikolaj B\u00f8ggild","id":"778"},{"ID":"656","user_login":"nikolaj.christensen","display_name":"Nikolaj Christensen","id":"656"},{"ID":"73","user_login":"nikolaj.holland","display_name":"Nikolaj Holland","id":"73"},{"ID":"660","user_login":"nikolaj.knage","display_name":"Nikolaj Knage","id":"660"},{"ID":"806","user_login":"nikolaj.maansson","display_name":"Nikolaj M\u00e5nsson","id":"806"},{"ID":"800","user_login":"nikolaj.meyer","display_name":"Nikolaj Meyer","id":"800"},{"ID":"952","user_login":"nikolaj.wiesauer","display_name":"Nikolaj Wiesauer","id":"952"},{"ID":"587","user_login":"nils.korsager","display_name":"Nils Korsager","id":"587"},{"ID":"535","user_login":"nils.valentin","display_name":"nils valentin","id":"535"},{"ID":"992","user_login":"nina.brander","display_name":"Nina Brander","id":"992"},{"ID":"1174","user_login":"nina.cedergreen","display_name":"Nina Cedergreen","id":"1174"},{"ID":"68","user_login":"nis.jakobsen","display_name":"Nis Jakobsen","id":"68"},{"ID":"22","user_login":"olav lilleholt.schjoerring","display_name":"Olav Lilleholt Schj\u00f8rring","id":"22"},{"ID":"1041","user_login":"olav.erlendsson","display_name":"Olav Erlendsson","id":"1041"},{"ID":"167","user_login":"olavur.thorup","display_name":"Olavur Thorup","id":"167"},{"ID":"1289","user_login":"ole birk.leegaard","display_name":"Ole Birk Leegaard","id":"1289"},{"ID":"810","user_login":"ole chr.hansen","display_name":"Ole Chr Hansen","id":"810"},{"ID":"851","user_login":"ole helvig.jensen","display_name":"Ole Helvig Jensen","id":"851"},{"ID":"1043","user_login":"ole pagh.mathiesen","display_name":"Ole Pagh Mathiesen","id":"1043"},{"ID":"735","user_login":"ole pagh.svendsen","display_name":"Ole Pagh Svendsen","id":"735"},{"ID":"955","user_login":"ole reimer.teglbjaerg","display_name":"Ole Reimer Teglbj\u00e6rg","id":"955"},{"ID":"28","user_login":"ole steen.sandberg","display_name":"Ole Steen Sandberg","id":"28"},{"ID":"596","user_login":"ole veksoe.olsen","display_name":"Ole Veks\u00f8 Olsen","id":"596"},{"ID":"244","user_login":"ole.andersen","display_name":"Ole Andersen","id":"244"},{"ID":"440","user_login":"ole.bang","display_name":"Ole Bang","id":"440"},{"ID":"616","user_login":"ole.caspersen","display_name":"Ole Caspersen","id":"616"},{"ID":"484","user_login":"ole.daugaard","display_name":"Ole Daugaard","id":"484"},{"ID":"239","user_login":"ole.johansen","display_name":"Ole Johansen","id":"239"},{"ID":"1138","user_login":"ole.korsholm","display_name":"Ole Korsholm","id":"1138"},{"ID":"447","user_login":"ole.lindholm andersen","display_name":"Ole Lindholm Andersen","id":"447"},{"ID":"1226","user_login":"ole.moeller dall","display_name":"Ole M\u00f8ller Dall","id":"1226"},{"ID":"413","user_login":"ole.oersted","display_name":"Ole \u00d8rsted","id":"413"},{"ID":"921","user_login":"ole.roem","display_name":"Ole R\u00f8m","id":"921"},{"ID":"556","user_login":"ole.skjold","display_name":"Ole skjold","id":"556"},{"ID":"1200","user_login":"ole.smedegaard","display_name":"Ole Smedegaard","id":"1200"},{"ID":"666","user_login":"ole.westergaard","display_name":"Ole Westergaard","id":"666"},{"ID":"799","user_login":"oliver.schoesler","display_name":"Oliver Sch\u00f8sler","id":"799"},{"ID":"515","user_login":"olsen.jan","display_name":"Olsen Jan","id":"515"},{"ID":"570","user_login":"oluf.eriksen","display_name":"Oluf Eriksen","id":"570"},{"ID":"285","user_login":"oscar.brugger","display_name":"Oscar Br\u00fcgger","id":"285"},{"ID":"845","user_login":"oscar.buhl","display_name":"Oscar Buhl","id":"845"},{"ID":"647","user_login":"otilia.vindfeldt jensen","display_name":"Otilia Vindfeldt Jensen","id":"647"},{"ID":"249","user_login":"paal.heick","display_name":"P\u00e5l Heick","id":"249"},{"ID":"1113","user_login":"palle.groenbaek","display_name":"Palle Gr\u00f8nb\u00e6k","id":"1113"},{"ID":"40","user_login":"patrick.bjerregaard","display_name":"Patrick Bjerregaard","id":"40"},{"ID":"369","user_login":"patrick.rahbek weile","display_name":"Patrick Rahbek Weile","id":"369"},{"ID":"1071","user_login":"paul.christiansen","display_name":"Paul Christiansen","id":"1071"},{"ID":"112","user_login":"paul.djurhuus","display_name":"Paul Djurhuus","id":"112"},{"ID":"976","user_login":"paw.hallandson","display_name":"Paw Hallandson","id":"976"},{"ID":"675","user_login":"peder.jensen","display_name":"Peder Jensen","id":"675"},{"ID":"628","user_login":"peder.pedersen","display_name":"PEDER PEDERSEN","id":"628"},{"ID":"36","user_login":"peer.larsen","display_name":"Peer Larsen","id":"36"},{"ID":"1060","user_login":"pelle.dalsgaard-petersen","display_name":"Pelle Dalsgaard-Petersen","id":"1060"},{"ID":"1067","user_login":"pelle.garbus","display_name":"Pelle Garbus","id":"1067"},{"ID":"1024","user_login":"pelle.moerk","display_name":"Pelle M\u00f8rk","id":"1024"},{"ID":"600","user_login":"per dalum.laursen","display_name":"Per Dalum Laursen","id":"600"},{"ID":"1123","user_login":"per dunk.pedersen","display_name":"Per Dunk Pedersen","id":"1123"},{"ID":"65","user_login":"per k m.andersen","display_name":"Per K M Andersen","id":"65"},{"ID":"463","user_login":"per sax.moeller","display_name":"PER SAX M\u00d8LLER","id":"463"},{"ID":"1161","user_login":"per.bech","display_name":"Per Bech","id":"1161"},{"ID":"612","user_login":"per.birch","display_name":"Per Birch","id":"612"},{"ID":"1284","user_login":"per.crillesen","display_name":"Per Crillesen","id":"1284"},{"ID":"1115","user_login":"per.dam","display_name":"Per Dam","id":"1115"},{"ID":"926","user_login":"per.hansen","display_name":"Per Hansen","id":"926"},{"ID":"1163","user_login":"per.jensen","display_name":"Per Jensen","id":"1163"},{"ID":"724","user_login":"per.jespersen","display_name":"Per Jespersen","id":"724"},{"ID":"355","user_login":"per.krog","display_name":"Per Krog","id":"355"},{"ID":"9","user_login":"per.mikkelsen","display_name":"Per Mikkelsen","id":"9"},{"ID":"1280","user_login":"per.soejberg","display_name":"Per S\u00f8jberg","id":"1280"},{"ID":"332","user_login":"per.tork larsen","display_name":"Per Tork Larsen","id":"332"},{"ID":"1094","user_login":"pernille.steinhauer","display_name":"Pernille Steinhauer","id":"1094"},{"ID":"1046","user_login":"peter bernstorff.schroeder","display_name":"Peter Bernstorff Schr\u00f8der","id":"1046"},{"ID":"204","user_login":"peter bjoern.heinze","display_name":"Peter Bj\u00f8rn Heinze","id":"204"},{"ID":"752","user_login":"peter frank.wenzel","display_name":"Peter Frank Wenzel","id":"752"},{"ID":"234","user_login":"peter klingspor.rasmussen","display_name":"Peter Klingspor Rasmussen","id":"234"},{"ID":"1281","user_login":"peter.aspe","display_name":"Peter Aspe","id":"1281"},{"ID":"109","user_login":"peter.baard larsen","display_name":"Peter B\u00e5rd Larsen","id":"109"},{"ID":"313","user_login":"peter.bjerre","display_name":"Peter Bjerre","id":"313"},{"ID":"557","user_login":"peter.bonde","display_name":"Peter Bonde","id":"557"},{"ID":"989","user_login":"peter.faber","display_name":"Peter Faber","id":"989"},{"ID":"774","user_login":"peter.friborg","display_name":"Peter Friborg","id":"774"},{"ID":"819","user_login":"peter.humaidan","display_name":"Peter Humaidan","id":"819"},{"ID":"238","user_login":"peter.johansen","display_name":"Peter Johansen","id":"238"},{"ID":"1114","user_login":"peter.kelnaes","display_name":"Peter Keln\u00e6s","id":"1114"},{"ID":"14","user_login":"peter.kleist","display_name":"Peter Kleist","id":"14"},{"ID":"911","user_login":"peter.krarup","display_name":"Peter Krarup","id":"911"},{"ID":"751","user_login":"peter.kristensen","display_name":"Peter Kristensen","id":"751"},{"ID":"808","user_login":"peter.larsen","display_name":"Peter Larsen","id":"808"},{"ID":"1196","user_login":"peter.lyholm soerensen","display_name":"Peter Lyholm S\u00f8rensen","id":"1196"},{"ID":"393","user_login":"peter.mouritzen","display_name":"Peter Mouritzen","id":"393"},{"ID":"520","user_login":"peter.nedergaard","display_name":"Peter Nedergaard","id":"520"},{"ID":"772","user_login":"peter.nielsen","display_name":"Peter Nielsen","id":"772"},{"ID":"32","user_login":"peter.olsen","display_name":"Peter Olsen","id":"32"},{"ID":"436","user_login":"peter.palshoej","display_name":"Peter Palsh\u00f8j","id":"436"},{"ID":"132","user_login":"peter.rasmussen","display_name":"Peter Rasmussen","id":"132"},{"ID":"1086","user_login":"peter.schaldemose","display_name":"Peter Schaldemose","id":"1086"},{"ID":"493","user_login":"peter.schoubye","display_name":"peter schoubye","id":"493"},{"ID":"1218","user_login":"peter.schoubye-5225","display_name":"Peter Schoubye","id":"1218"},{"ID":"899","user_login":"peter.skjelmose","display_name":"Peter Skjelmose","id":"899"},{"ID":"536","user_login":"peter.soedring","display_name":"Peter S\u00f8dring","id":"536"},{"ID":"228","user_login":"peter.soerensen","display_name":"Peter S\u00f8rensen","id":"228"},{"ID":"455","user_login":"peter.traberg","display_name":"Peter Traberg","id":"455"},{"ID":"1098","user_login":"peter.tranberg","display_name":"Peter Tranberg","id":"1098"},{"ID":"424","user_login":"peter.tunstall","display_name":"Peter Tunstall","id":"424"},{"ID":"1077","user_login":"peter.wolff","display_name":"Peter Wolff","id":"1077"},{"ID":"324","user_login":"peter.wollerup","display_name":"Peter Wollerup","id":"324"},{"ID":"1126","user_login":"petko.tsutsumanov","display_name":"Petko Tsutsumanov","id":"1126"},{"ID":"1229","user_login":"philip kaare.loeventoft","display_name":"Philip Kaare L\u00f8ventoft","id":"1229"},{"ID":"568","user_login":"philip.hagemann","display_name":"philip Hagemann","id":"568"},{"ID":"1089","user_login":"philip.maury","display_name":"Philip Maury","id":"1089"},{"ID":"1044","user_login":"philip.pfahl","display_name":"Philip Pfahl","id":"1044"},{"ID":"1141","user_login":"philip.prokesch","display_name":"Philip Prokesch","id":"1141"},{"ID":"865","user_login":"philip.soerensen","display_name":"Philip S\u00f8rensen","id":"865"},{"ID":"1231","user_login":"PhilipM","display_name":"PhilipM","id":"1231"},{"ID":"601","user_login":"pia bugge.konradsen","display_name":"Pia Bugge Konradsen","id":"601"},{"ID":"671","user_login":"pierre.frandsen","display_name":"Pierre Frandsen","id":"671"},{"ID":"1309","user_login":"poul erik.kristensen","display_name":"poul erik kristensen","id":"1309"},{"ID":"454","user_login":"poul-jan.petersen","display_name":"Poul-Jan Petersen","id":"454"},{"ID":"304","user_login":"poul.hansen","display_name":"poul hansen","id":"304"},{"ID":"144","user_login":"poul.ingildsen","display_name":"Poul Ingildsen","id":"144"},{"ID":"431","user_login":"poul.juul pedersen","display_name":"Poul Juul Pedersen","id":"431"},{"ID":"576","user_login":"poul.michelsen","display_name":"Poul Michelsen","id":"576"},{"ID":"316","user_login":"poul.rand","display_name":"Poul Rand","id":"316"},{"ID":"208","user_login":"povl.kvols jensen","display_name":"Povl Kvols Jensen","id":"208"},{"ID":"873","user_login":"preben.midtgaard","display_name":"Preben Midtgaard","id":"873"},{"ID":"528","user_login":"ragnar.herdalur","display_name":"Ragnar Herdalur","id":"528"},{"ID":"630","user_login":"ragner.webler","display_name":"Ragner Webler","id":"630"},{"ID":"1022","user_login":"rane.schjoett ahle","display_name":"Rane Schj\u00f8tt Ahle","id":"1022"},{"ID":"895","user_login":"rasmus bech.hansen","display_name":"Rasmus Bech Hansen","id":"895"},{"ID":"79","user_login":"rasmus dybbro.engelsholm","display_name":"Rasmus Dybbro Engelsholm","id":"79"},{"ID":"968","user_login":"rasmus holm.rislund","display_name":"Rasmus Holm Rislund","id":"968"},{"ID":"1188","user_login":"rasmus kaspar.jensen","display_name":"Rasmus Kaspar Jensen","id":"1188"},{"ID":"5","user_login":"Rasmus Toft-Petersen","display_name":"Rasmus Toft-Petersen","id":"5"},{"ID":"855","user_login":"rasmus.bengtsen","display_name":"Rasmus Bengtsen","id":"855"},{"ID":"246","user_login":"rasmus.dybkjaer","display_name":"Rasmus Dybkj\u00e6r","id":"246"},{"ID":"681","user_login":"rasmus.joergensen","display_name":"Rasmus J\u00f8rgensen","id":"681"},{"ID":"1014","user_login":"rasmus.kjeldsen","display_name":"Rasmus Kjeldsen","id":"1014"},{"ID":"67","user_login":"rasmus.kristensen","display_name":"Rasmus Kristensen","id":"67"},{"ID":"918","user_login":"rasmus.mogensen","display_name":"Rasmus Mogensen","id":"918"},{"ID":"1244","user_login":"rasmus.pold","display_name":"Rasmus Pold","id":"1244"},{"ID":"939","user_login":"rasmus.revsbeck","display_name":"Rasmus Revsbeck","id":"939"},{"ID":"964","user_login":"rasmus.schultz madsen","display_name":"Rasmus Schultz Madsen","id":"964"},{"ID":"352","user_login":"rasmus.thomsen","display_name":"Rasmus Thomsen","id":"352"},{"ID":"93","user_login":"rebecca.plomin","display_name":"Rebecca Plomin","id":"93"},{"ID":"211","user_login":"remy.holm","display_name":"Remy Holm","id":"211"},{"ID":"978","user_login":"rene.ditlevsen","display_name":"Ren\u00e9 Ditlevsen","id":"978"},{"ID":"1242","user_login":"rene.hansen","display_name":"Rene Hansen","id":"1242"},{"ID":"940","user_login":"rene.hilligsoee","display_name":"Rene Hilligs\u00f8e","id":"940"},{"ID":"705","user_login":"rene.hjorth","display_name":"Ren\u00e9 Hjorth","id":"705"},{"ID":"468","user_login":"rene.kobberoee","display_name":"Ren\u00e9 Kobber\u00f8e","id":"468"},{"ID":"514","user_login":"rene.maxwell","display_name":"Rene Maxwell","id":"514"},{"ID":"602","user_login":"rene.mikkelsen","display_name":"Ren\u00e9 Mikkelsen","id":"602"},{"ID":"261","user_login":"rene.peugeot","display_name":"Ren\u00e9 Peugeot","id":"261"},{"ID":"25","user_login":"rene.rosengren","display_name":"Ren\u00e9 Rosengren","id":"25"},{"ID":"473","user_login":"rene.varming","display_name":"Ren\u00e9 Varming","id":"473"},{"ID":"173","user_login":"richard.nielsen","display_name":"Richard Nielsen","id":"173"},{"ID":"1225","user_login":"richard.nielsen-3604","display_name":"Richard Nielsen","id":"1225"},{"ID":"1278","user_login":"richford.ekholm","display_name":"Richford Ekholm","id":"1278"},{"ID":"430","user_login":"rikke.mousten","display_name":"Rikke Mousten","id":"430"},{"ID":"795","user_login":"rikke.norlyk","display_name":"Rikke Norlyk","id":"795"},{"ID":"1187","user_login":"robert.joensson","display_name":"Robert J\u00f8nsson","id":"1187"},{"ID":"116","user_login":"rolf.garde","display_name":"Rolf Garde","id":"116"},{"ID":"38","user_login":"rolf.hansen","display_name":"Rolf Hansen","id":"38"},{"ID":"299","user_login":"ronny van.tieu christiansen","display_name":"Ronny Van Tieu Christiansen","id":"299"},{"ID":"783","user_login":"ruben wendelboe.hansen","display_name":"Ruben Wendelboe Hansen","id":"783"},{"ID":"597","user_login":"rufus.larsen","display_name":"Rufus Larsen","id":"597"},{"ID":"406","user_login":"rune thornelius.olsen","display_name":"Rune Thornelius Olsen","id":"406"},{"ID":"1095","user_login":"rune.alleslev","display_name":"Rune Alleslev","id":"1095"},{"ID":"1088","user_login":"rune.christensen","display_name":"Rune Christensen","id":"1088"},{"ID":"367","user_login":"rune.henvig","display_name":"Rune Henvig","id":"367"},{"ID":"1039","user_login":"rune.madsen","display_name":"Rune Madsen","id":"1039"},{"ID":"698","user_login":"rune.pedersen","display_name":"Rune Pedersen","id":"698"},{"ID":"749","user_login":"rune.schou","display_name":"Rune Schou","id":"749"},{"ID":"375","user_login":"rune.tjoernild","display_name":"Rune Tj\u00f8rnild","id":"375"},{"ID":"657","user_login":"rune.venborg","display_name":"Rune Venborg","id":"657"},{"ID":"626","user_login":"rune.westrup","display_name":"Rune Westrup","id":"626"},{"ID":"991","user_login":"s bartels.rasmussen","display_name":"S Bartels Rasmussen","id":"991"},{"ID":"51","user_login":"samir.ben chaabane","display_name":"Samir Ben Chaabane","id":"51"},{"ID":"395","user_login":"sara.moenster ditlev","display_name":"Sara M\u00f8nster Ditlev","id":"395"},{"ID":"318","user_login":"sdfgsg","display_name":"sdfgsg","id":"318"},{"ID":"271","user_login":"sean.pedersen","display_name":"Sean Pedersen","id":"271"},{"ID":"770","user_login":"sean.sealey","display_name":"Sean Sealey","id":"770"},{"ID":"45","user_login":"sean.seidelin","display_name":"Sean Seidelin","id":"45"},{"ID":"864","user_login":"sebastian nordenlund.nissen","display_name":"Sebastian Nordenlund Nissen","id":"864"},{"ID":"942","user_login":"sebastian.lynge","display_name":"Sebastian Lynge","id":"942"},{"ID":"957","user_login":"sebastian.mosegaard","display_name":"Sebastian Mosegaard","id":"957"},{"ID":"782","user_login":"sebastian.mrzyglod","display_name":"Sebastian Mrzyglod","id":"782"},{"ID":"451","user_login":"sebastian.stoeckler","display_name":"Sebastian St\u00f8ckler","id":"451"},{"ID":"1212","user_login":"SEO","display_name":"S\u00f8ren","id":"1212"},{"ID":"709","user_login":"sigurd.okkels","display_name":"Sigurd Okkels","id":"709"},{"ID":"997","user_login":"sigurd.storgaard","display_name":"Sigurd Storgaard","id":"997"},{"ID":"427","user_login":"silja.arenfeldt","display_name":"Silja Arenfeldt","id":"427"},{"ID":"971","user_login":"silke.kirk","display_name":"Silke Kirk","id":"971"},{"ID":"1135","user_login":"simon vilsboell.sundgaard","display_name":"Simon Vilsb\u00f8ll Sundgaard","id":"1135"},{"ID":"906","user_login":"simon.baekkegaard","display_name":"Simon B\u00e6kkegaard","id":"906"},{"ID":"784","user_login":"simon.granath","display_name":"Simon Granath","id":"784"},{"ID":"858","user_login":"simon.guldbaek","display_name":"Simon Guldb\u00e6k","id":"858"},{"ID":"102","user_login":"simon.heisterkamp","display_name":"Simon Heisterkamp","id":"102"},{"ID":"958","user_login":"simon.jakobsen","display_name":"Simon Jakobsen","id":"958"},{"ID":"519","user_login":"simon.kreuzfeldt","display_name":"Simon Kreuzfeldt","id":"519"},{"ID":"868","user_login":"simon.moenster","display_name":"Simon M\u00f8nster","id":"868"},{"ID":"983","user_login":"simon.noergaard","display_name":"Simon N\u00f8rgaard","id":"983"},{"ID":"126","user_login":"simon.olesen","display_name":"Simon Olesen","id":"126"},{"ID":"55","user_login":"simon.pedersen","display_name":"Simon Pedersen","id":"55"},{"ID":"773","user_login":"simon.rasmussen","display_name":"Simon Rasmussen","id":"773"},{"ID":"1290","user_login":"simon.valkaer","display_name":"Simon Valk\u00e6r","id":"1290"},{"ID":"1194","user_login":"soeren beck.nielsen","display_name":"S\u00f8ren Beck Nielsen","id":"1194"},{"ID":"278","user_login":"soeren hoennicke.toft","display_name":"S\u00f8ren H\u00f8nnicke Toft","id":"278"},{"ID":"135","user_login":"soeren isak.abramsson","display_name":"S\u00f8ren Isak Abramsson","id":"135"},{"ID":"1033","user_login":"soeren juul.moeller","display_name":"S\u00f8ren Juul M\u00f8ller","id":"1033"},{"ID":"1011","user_login":"soeren mikkel.nielsen","display_name":"S\u00f8ren Mikkel Nielsen","id":"1011"},{"ID":"502","user_login":"soeren mose.hansen","display_name":"S\u00f8ren Mose Hansen","id":"502"},{"ID":"344","user_login":"soeren peter.joergensen","display_name":"S\u00f8ren Peter J\u00f8rgensen","id":"344"},{"ID":"134","user_login":"soeren peter.pedersen","display_name":"S\u00f8ren Peter Pedersen","id":"134"},{"ID":"836","user_login":"soeren.andersen","display_name":"S\u00f8ren Andersen","id":"836"},{"ID":"260","user_login":"soeren.bloch","display_name":"S\u00f8ren Bloch","id":"260"},{"ID":"552","user_login":"soeren.brunslev","display_name":"S\u00f8ren Brunslev","id":"552"},{"ID":"764","user_login":"soeren.bryder","display_name":"S\u00f8ren Bryder","id":"764"},{"ID":"1258","user_login":"soeren.juul","display_name":"S\u00f8ren Juul","id":"1258"},{"ID":"1155","user_login":"soeren.kudsk","display_name":"S\u00f8ren Kudsk","id":"1155"},{"ID":"1157","user_login":"soeren.lind","display_name":"S\u00f8ren Lind","id":"1157"},{"ID":"171","user_login":"soeren.lyngesen","display_name":"S\u00f8ren Lyngesen","id":"171"},{"ID":"199","user_login":"soeren.lyngesen-4574","display_name":"S\u00f8ren Lyngesen","id":"199"},{"ID":"262","user_login":"soeren.mousten","display_name":"S\u00f8ren Mousten","id":"262"},{"ID":"13","user_login":"soeren.nielsen","display_name":"S\u00f8ren Nielsen","id":"13"},{"ID":"1069","user_login":"soeren.nielsen-3007","display_name":"S\u00f8ren Nielsen","id":"1069"},{"ID":"374","user_login":"soeren.ohlhues","display_name":"S\u00d8REN OHLHUES","id":"374"},{"ID":"646","user_login":"soeren.padkjaer","display_name":"S\u00f8ren Padkj\u00e6r","id":"646"},{"ID":"320","user_login":"soeren.purup","display_name":"S\u00f8ren Purup","id":"320"},{"ID":"490","user_login":"soeren.rasmussen","display_name":"S\u00f8ren Rasmussen","id":"490"},{"ID":"1293","user_login":"soeren.regenberg","display_name":"S\u00f8ren Regenberg","id":"1293"},{"ID":"700","user_login":"soeren.skamris jeppesen","display_name":"S\u00f8ren Skamris jeppesen","id":"700"},{"ID":"174","user_login":"soeren.storm","display_name":"S\u00f8ren Storm","id":"174"},{"ID":"1232","user_login":"soeren.weimann","display_name":"S\u00f8ren Weimann","id":"1232"},{"ID":"111","user_login":"soeren.winther lundby","display_name":"S\u00f8ren Winther Lundby","id":"111"},{"ID":"268","user_login":"sofie.telling","display_name":"Sofie Telling","id":"268"},{"ID":"212","user_login":"sofus roenne.soltau","display_name":"Sofus R\u00f8nne Soltau","id":"212"},{"ID":"399","user_login":"sonja.holm-dahlin","display_name":"Sonja Holm-Dahlin","id":"399"},{"ID":"885","user_login":"steen alfred.oerndorf","display_name":"Steen Alfred \u00d8rndorf","id":"885"},{"ID":"791","user_login":"steen.christensen","display_name":"Steen Christensen","id":"791"},{"ID":"197","user_login":"steen.larsen","display_name":"Steen Larsen","id":"197"},{"ID":"898","user_login":"steen.nygaard","display_name":"Steen Nygaard","id":"898"},{"ID":"1205","user_login":"steen.rasmussen","display_name":"Steen Rasmussen","id":"1205"},{"ID":"1179","user_login":"steen.wibling","display_name":"Steen Wibling","id":"1179"},{"ID":"941","user_login":"stefan.johansen","display_name":"Stefan Johansen","id":"941"},{"ID":"1239","user_login":"stefan.lindstam","display_name":"Stefan Lindstam","id":"1239"},{"ID":"523","user_login":"stefan.mejlgaard","display_name":"Stefan Mejlgaard","id":"523"},{"ID":"252","user_login":"stefan.micheelsen","display_name":"Stefan Micheelsen","id":"252"},{"ID":"1274","user_login":"stefan.nielsen","display_name":"Stefan Nielsen","id":"1274"},{"ID":"995","user_login":"steffen g..moeller","display_name":"Steffen G. M\u00f8ller","id":"995"},{"ID":"449","user_login":"steffen griberg.moeller","display_name":"Steffen Griberg M\u00f8ller","id":"449"},{"ID":"83","user_login":"steffen.frederiksen","display_name":"Steffen Frederiksen","id":"83"},{"ID":"233","user_login":"steffen.hansen","display_name":"Steffen Hansen","id":"233"},{"ID":"339","user_login":"steffen.hoeegh","display_name":"Steffen H\u00f8egh","id":"339"},{"ID":"326","user_login":"steffen.moeller","display_name":"Steffen M\u00f8ller","id":"326"},{"ID":"624","user_login":"steffen.sinning","display_name":"Steffen Sinning","id":"624"},{"ID":"70","user_login":"steffen.thomsen","display_name":"steffen Thomsen","id":"70"},{"ID":"175","user_login":"steffen.thomsen-7501","display_name":"Steffen Thomsen","id":"175"},{"ID":"986","user_login":"sten.bergstrom","display_name":"Sten Bergstr\u00f6m","id":"986"},{"ID":"218","user_login":"sten.byriel","display_name":"Sten Byriel","id":"218"},{"ID":"410","user_login":"stephen.buckley","display_name":"Stephen Buckley","id":"410"},{"ID":"1282","user_login":"stig rask.olesen","display_name":"Stig Rask Olesen","id":"1282"},{"ID":"546","user_login":"stig.boeckel","display_name":"Stig B\u00f8ckel","id":"546"},{"ID":"351","user_login":"stig.rasmusden","display_name":"Stig Rasmusden","id":"351"},{"ID":"606","user_login":"stine dahlstroem.laursen","display_name":"Stine Dahlstr\u00f8m Laursen","id":"606"},{"ID":"185","user_login":"stine.jacobsen","display_name":"Stine Jacobsen","id":"185"},{"ID":"412","user_login":"sune.jensen","display_name":"Sune Jensen","id":"412"},{"ID":"712","user_login":"sven.tornvig","display_name":"Sven Tornvig","id":"712"},{"ID":"465","user_login":"svend west.hansen","display_name":"Svend West Hansen","id":"465"},{"ID":"1286","user_login":"svend.andersen","display_name":"svend andersen","id":"1286"},{"ID":"789","user_login":"svend.bastiansen","display_name":"Svend Bastiansen","id":"789"},{"ID":"929","user_login":"svend.nielsen","display_name":"Svend Nielsen","id":"929"},{"ID":"584","user_login":"svend.poulsen","display_name":"Svend Poulsen","id":"584"},{"ID":"792","user_login":"svend.steenstrup","display_name":"Svend Steenstrup","id":"792"},{"ID":"509","user_login":"sylvester.stormby-szollosi","display_name":"Sylvester Stormby-Sz\u00f6ll\u00f6si","id":"509"},{"ID":"456","user_login":"test.test","display_name":"Test Test","id":"456"},{"ID":"717","user_login":"test.test-4982","display_name":"Test Test","id":"717"},{"ID":"3","user_login":"Theis","display_name":"Theis Palm","id":"3"},{"ID":"796","user_login":"theis lyng.reinvang","display_name":"Theis Lyng Reinvang","id":"796"},{"ID":"1068","user_login":"theis.andersen","display_name":"Theis Andersen","id":"1068"},{"ID":"738","user_login":"theis.kjeldsen","display_name":"Theis Kjeldsen","id":"738"},{"ID":"825","user_login":"theis.noerskov","display_name":"Theis N\u00f8rskov","id":"825"},{"ID":"1228","user_login":"theodor.simonsen","display_name":"Theodor Simonsen","id":"1228"},{"ID":"788","user_login":"thimas.knudsen","display_name":"Thimas Knudsen","id":"788"},{"ID":"740","user_login":"thomas bay.wedeby","display_name":"Thomas Bay Wedeby","id":"740"},{"ID":"108","user_login":"thomas gerth.andersen","display_name":"Thomas Gerth Andersen","id":"108"},{"ID":"613","user_login":"thomas holst.regnarsson","display_name":"Thomas Holst Regnarsson","id":"613"},{"ID":"283","user_login":"thomas isak.sandvej","display_name":"Thomas Isak Sandvej","id":"283"},{"ID":"1109","user_login":"thomas loeve.lund","display_name":"Thomas L\u00f8ve Lund","id":"1109"},{"ID":"186","user_login":"thomas rosenlund.frederiksen","display_name":"Thomas Rosenlund Frederiksen","id":"186"},{"ID":"216","user_login":"thomas schoubye.poulsen","display_name":"Thomas Schoubye Poulsen","id":"216"},{"ID":"1058","user_login":"thomas therkel.nielsen","display_name":"Thomas Therkel Nielsen","id":"1058"},{"ID":"907","user_login":"thomas.albrecht-beste","display_name":"Thomas Albrecht-Beste","id":"907"},{"ID":"1027","user_login":"thomas.andresen","display_name":"Thomas Andresen","id":"1027"},{"ID":"54","user_login":"thomas.ansbjerg","display_name":"Thomas Ansbjerg","id":"54"},{"ID":"801","user_login":"thomas.bakke","display_name":"Thomas Bakke","id":"801"},{"ID":"551","user_login":"thomas.christiansen","display_name":"Thomas Christiansen","id":"551"},{"ID":"710","user_login":"thomas.cotzand","display_name":"Thomas Cotzand","id":"710"},{"ID":"909","user_login":"thomas.damm","display_name":"Thomas Damm","id":"909"},{"ID":"1010","user_login":"thomas.danielsen","display_name":"Thomas Danielsen","id":"1010"},{"ID":"766","user_login":"thomas.dessau","display_name":"Thomas Dessau","id":"766"},{"ID":"629","user_login":"thomas.egebak","display_name":"Thomas Egebak","id":"629"},{"ID":"893","user_login":"thomas.elkrog","display_name":"thomas Elkrog","id":"893"},{"ID":"1045","user_login":"thomas.graversen","display_name":"Thomas Graversen","id":"1045"},{"ID":"869","user_login":"thomas.greve","display_name":"Thomas Greve","id":"869"},{"ID":"130","user_login":"thomas.guldmann","display_name":"Thomas Guldmann","id":"130"},{"ID":"1235","user_login":"thomas.holte","display_name":"Thomas Holte","id":"1235"},{"ID":"711","user_login":"thomas.huus munche moeller","display_name":"Thomas Huus Munche M\u00f8ller","id":"711"},{"ID":"1052","user_login":"thomas.joergensen","display_name":"Thomas J\u00f8rgensen","id":"1052"},{"ID":"364","user_login":"thomas.johansen","display_name":"Thomas Johansen","id":"364"},{"ID":"121","user_login":"thomas.kabel","display_name":"Thomas Kabel","id":"121"},{"ID":"754","user_login":"thomas.kleis","display_name":"Thomas Kleis","id":"754"},{"ID":"842","user_login":"thomas.krap","display_name":"Thomas Krap","id":"842"},{"ID":"972","user_login":"thomas.larsen","display_name":"Thomas Larsen","id":"972"},{"ID":"1085","user_login":"thomas.larsen-8927","display_name":"Thomas Larsen","id":"1085"},{"ID":"1037","user_login":"thomas.lund joergensen","display_name":"Thomas Lund J\u00f8rgensen","id":"1037"},{"ID":"826","user_login":"thomas.lundgaard","display_name":"Thomas Lundgaard","id":"826"},{"ID":"46","user_login":"thomas.moelgaard","display_name":"Thomas M\u00f8lgaard","id":"46"},{"ID":"875","user_login":"thomas.munter","display_name":"Thomas M\u00fcnter","id":"875"},{"ID":"802","user_login":"thomas.noergaard","display_name":"Thomas N\u00f8rgaard","id":"802"},{"ID":"49","user_login":"thomas.petersen","display_name":"Thomas Petersen","id":"49"},{"ID":"416","user_login":"thomas.petersen-7240","display_name":"Thomas Petersen","id":"416"},{"ID":"151","user_login":"thomas.petersen-9326","display_name":"Thomas Petersen","id":"151"},{"ID":"276","user_login":"thomas.rasmussen","display_name":"Thomas Rasmussen","id":"276"},{"ID":"143","user_login":"thomas.smidt kersting","display_name":"Thomas Smidt Kersting","id":"143"},{"ID":"106","user_login":"thomas.staunsbjerg","display_name":"Thomas Staunsbjerg","id":"106"},{"ID":"114","user_login":"thor.autzen","display_name":"Thor Autzen","id":"114"},{"ID":"215","user_login":"thor.borne","display_name":"Thor Borne","id":"215"},{"ID":"1097","user_login":"thorkild.jakobsen","display_name":"Thorkild Jakobsen","id":"1097"},{"ID":"127","user_login":"tim feveile sejr.hansen","display_name":"Tim Feveile Sejr Hansen","id":"127"},{"ID":"1119","user_login":"tim.lauridsen","display_name":"Tim Lauridsen","id":"1119"},{"ID":"677","user_login":"tina.petersen","display_name":"Tina Petersen","id":"677"},{"ID":"398","user_login":"tina.sparre","display_name":"Tina Sparre","id":"398"},{"ID":"1001","user_login":"tino.taylor nielsen","display_name":"Tino Taylor Nielsen","id":"1001"},{"ID":"904","user_login":"tobias engelhardt.rasmussen","display_name":"Tobias Engelhardt Rasmussen","id":"904"},{"ID":"840","user_login":"tobias jul.kastrup","display_name":"Tobias Jul Kastrup","id":"840"},{"ID":"621","user_login":"tobias.jarrett","display_name":"Tobias Jarrett","id":"621"},{"ID":"1023","user_login":"tobias.johannessen","display_name":"Tobias Johannessen","id":"1023"},{"ID":"897","user_login":"tobias.piechowiak","display_name":"Tobias Piechowiak","id":"897"},{"ID":"241","user_login":"tobias.steffensen","display_name":"Tobias Steffensen","id":"241"},{"ID":"243","user_login":"tobias.steffensen-6557","display_name":"Tobias Steffensen","id":"243"},{"ID":"319","user_login":"toke.bohm","display_name":"Toke Bohm","id":"319"},{"ID":"780","user_login":"toke.vibel","display_name":"Toke Vibel","id":"780"},{"ID":"637","user_login":"tom.christensen","display_name":"Tom Christensen","id":"637"},{"ID":"553","user_login":"tomas.antoncik","display_name":"Tomas Antoncik","id":"553"},{"ID":"486","user_login":"tomas.gorrissen","display_name":"Tomas Gorrissen","id":"486"},{"ID":"607","user_login":"tomas.gorrissen-1227","display_name":"Tomas Gorrissen","id":"607"},{"ID":"1128","user_login":"tommy bech.kristiansen","display_name":"Tommy Bech Kristiansen","id":"1128"},{"ID":"461","user_login":"tommy.andresen","display_name":"Tommy Andresen","id":"461"},{"ID":"1256","user_login":"tommy.holmberg","display_name":"Tommy Holmberg","id":"1256"},{"ID":"538","user_login":"tommy.kobberoee","display_name":"Tommy Kobber\u00f8e","id":"538"},{"ID":"386","user_login":"tonny.soerensen","display_name":"Tonny S\u00f8rensen","id":"386"},{"ID":"924","user_login":"tor alvur halvdan.vikingur","display_name":"T\u00f3r \u00c1lvur Halvdan V\u00edkingur","id":"924"},{"ID":"396","user_login":"torben.christensen","display_name":"Torben Christensen","id":"396"},{"ID":"903","user_login":"torben.hauge","display_name":"Torben Hauge","id":"903"},{"ID":"668","user_login":"torben.lagoni","display_name":"Torben Lagoni","id":"668"},{"ID":"481","user_login":"torben.larsen","display_name":"Torben Larsen","id":"481"},{"ID":"85","user_login":"torben.lisby","display_name":"Torben Lisby","id":"85"},{"ID":"82","user_login":"torben.lucas","display_name":"Torben Lucas","id":"82"},{"ID":"541","user_login":"torben.noerskov","display_name":"Torben N\u00f8rskov","id":"541"},{"ID":"487","user_login":"torben.rasmussen","display_name":"Torben Rasmussen","id":"487"},{"ID":"16","user_login":"torben.rose","display_name":"Torben Rose","id":"16"},{"ID":"349","user_login":"torben.soenderby","display_name":"Torben S\u00f8nderby","id":"349"},{"ID":"856","user_login":"torben.soerensen","display_name":"Torben S\u00f8rensen","id":"856"},{"ID":"615","user_login":"torben.strandgaard","display_name":"Torben Strandgaard","id":"615"},{"ID":"1083","user_login":"torben.vindeloev","display_name":"Torben Vindel\u00f8v","id":"1083"},{"ID":"832","user_login":"torbjoern.lien kjaer","display_name":"Torbj\u00f8rn Lien Kj\u00e6r","id":"832"},{"ID":"293","user_login":"torsten.bille","display_name":"Torsten Bille","id":"293"},{"ID":"542","user_login":"torsten.brovang","display_name":"Torsten Brovang","id":"542"},{"ID":"29","user_login":"trine.lassen","display_name":"Trine Lassen","id":"29"},{"ID":"354","user_login":"troels.bay-petersen","display_name":"Troels Bay-Petersen","id":"354"},{"ID":"222","user_login":"troels.christensen","display_name":"Troels Christensen","id":"222"},{"ID":"420","user_login":"troels.christensen-7168","display_name":"Troels Christensen","id":"420"},{"ID":"334","user_login":"troels.feld","display_name":"Troels Feld","id":"334"},{"ID":"761","user_login":"troels.larsen","display_name":"Troels Larsen","id":"761"},{"ID":"954","user_login":"troels.oeland","display_name":"Troels \u00d8land","id":"954"},{"ID":"694","user_login":"troels.tousgaard","display_name":"Troels Tousgaard","id":"694"},{"ID":"655","user_login":"uffe dalager.skjold","display_name":"Uffe Dalager Skjold","id":"655"},{"ID":"1206","user_login":"uffe.eriksen","display_name":"Uffe Eriksen","id":"1206"},{"ID":"852","user_login":"ulla.nielsen","display_name":"Ulla Nielsen","id":"852"},{"ID":"990","user_login":"ulrich.hoelgaard","display_name":"Ulrich Hoelgaard","id":"990"},{"ID":"889","user_login":"varming.asger","display_name":"Varming Asger","id":"889"},{"ID":"296","user_login":"verner.villensgaard","display_name":"Verner Villensgaard","id":"296"},{"ID":"732","user_login":"viktor.konglevoll","display_name":"Viktor Konglevoll","id":"732"},{"ID":"759","user_login":"walther.rasmussen","display_name":"Walther Rasmussen","id":"759"},{"ID":"310","user_login":"wilhelm ditlev christian.thomsen","display_name":"Wilhelm Ditlev Christian Thomsen","id":"310"},{"ID":"353","user_login":"william.feely","display_name":"William Feely","id":"353"},{"ID":"573","user_login":"yvonne.thygesen","display_name":"Yvonne Thygesen","id":"573"},{"ID":"1025","user_login":"zarah.zimling","display_name":"Zarah Zimling","id":"1025"}],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.10 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>PUREX - genbehandlingsmetoden - Foreningen Atomkraft Ja Tak<\/title>\n<meta name=\"description\" content=\"PUREX (Plutonium Uranium Extraction) er en kemisk proces, der anvendes til at udvinde plutonium og uran fra brugt br\u00e6ndsel i reaktorer\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.atomkraft-jatak.dk\/newsite\/dokumenter\/purex-genbehandlingsmetode\/\" \/>\n<meta property=\"og:locale\" content=\"da_DK\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PUREX - genbehandlingsmetoden - Foreningen Atomkraft Ja Tak\" \/>\n<meta property=\"og:description\" content=\"PUREX (Plutonium Uranium Extraction) er en kemisk proces, der anvendes til at udvinde plutonium og uran fra brugt br\u00e6ndsel i reaktorer\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.atomkraft-jatak.dk\/newsite\/dokumenter\/purex-genbehandlingsmetode\/\" \/>\n<meta property=\"og:site_name\" content=\"Foreningen Atomkraft Ja Tak\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/atomkraftjatak\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-14T20:41:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.atomkraft-jatak.dk\/newsite\/wp-content\/uploads\/2023\/08\/image-26.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimeret l\u00e6setid\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutter\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.atomkraft-jatak.dk\/newsite\/dokumenter\/purex-genbehandlingsmetode\/\",\"url\":\"https:\/\/www.atomkraft-jatak.dk\/newsite\/dokumenter\/purex-genbehandlingsmetode\/\",\"name\":\"PUREX - genbehandlingsmetoden - Foreningen Atomkraft Ja Tak\",\"isPartOf\":{\"@id\":\"https:\/\/www.atomkraft-jatak.dk\/newsite\/#website\"},\"datePublished\":\"2023-08-13T14:19:13+00:00\",\"dateModified\":\"2024-09-14T20:41:02+00:00\",\"description\":\"PUREX (Plutonium Uranium Extraction) er en kemisk proces, der anvendes til at udvinde plutonium og uran fra brugt br\u00e6ndsel i reaktorer\",\"breadcrumb\":{\"@id\":\"https:\/\/www.atomkraft-jatak.dk\/newsite\/dokumenter\/purex-genbehandlingsmetode\/#breadcrumb\"},\"inLanguage\":\"da-DK\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.atomkraft-jatak.dk\/newsite\/dokumenter\/purex-genbehandlingsmetode\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.atomkraft-jatak.dk\/newsite\/dokumenter\/purex-genbehandlingsmetode\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.atomkraft-jatak.dk\/newsite\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Docs\",\"item\":\"https:\/\/www.atomkraft-jatak.dk\/newsite\/docs\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"PUREX &#8211; genbehandlingsmetoden\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.atomkraft-jatak.dk\/newsite\/#website\",\"url\":\"https:\/\/www.atomkraft-jatak.dk\/newsite\/\",\"name\":\"Foreningen Atomkraft Ja Tak\",\"description\":\"- Brug hjernen, split kernen\",\"publisher\":{\"@id\":\"https:\/\/www.atomkraft-jatak.dk\/newsite\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.atomkraft-jatak.dk\/newsite\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"da-DK\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.atomkraft-jatak.dk\/newsite\/#organization\",\"name\":\"Atomkraft Ja Tak\",\"url\":\"https:\/\/www.atomkraft-jatak.dk\/newsite\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"da-DK\",\"@id\":\"https:\/\/www.atomkraft-jatak.dk\/newsite\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.atomkraft-jatak.dk\/newsite\/wp-content\/uploads\/2021\/02\/logo-med-hjemmeside.png\",\"contentUrl\":\"https:\/\/www.atomkraft-jatak.dk\/newsite\/wp-content\/uploads\/2021\/02\/logo-med-hjemmeside.png\",\"width\":1452,\"height\":1470,\"caption\":\"Atomkraft Ja Tak\"},\"image\":{\"@id\":\"https:\/\/www.atomkraft-jatak.dk\/newsite\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/atomkraftjatak\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PUREX - genbehandlingsmetoden - Foreningen Atomkraft Ja Tak","description":"PUREX (Plutonium Uranium Extraction) er en kemisk proces, der anvendes til at udvinde plutonium og uran fra brugt br\u00e6ndsel i reaktorer","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.atomkraft-jatak.dk\/newsite\/dokumenter\/purex-genbehandlingsmetode\/","og_locale":"da_DK","og_type":"article","og_title":"PUREX - genbehandlingsmetoden - Foreningen Atomkraft Ja Tak","og_description":"PUREX (Plutonium Uranium Extraction) er en kemisk proces, der anvendes til at udvinde plutonium og uran fra brugt br\u00e6ndsel i reaktorer","og_url":"https:\/\/www.atomkraft-jatak.dk\/newsite\/dokumenter\/purex-genbehandlingsmetode\/","og_site_name":"Foreningen Atomkraft Ja Tak","article_publisher":"https:\/\/www.facebook.com\/atomkraftjatak\/","article_modified_time":"2024-09-14T20:41:02+00:00","og_image":[{"url":"https:\/\/www.atomkraft-jatak.dk\/newsite\/wp-content\/uploads\/2023\/08\/image-26.png"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimeret l\u00e6setid":"5 minutter"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.atomkraft-jatak.dk\/newsite\/dokumenter\/purex-genbehandlingsmetode\/","url":"https:\/\/www.atomkraft-jatak.dk\/newsite\/dokumenter\/purex-genbehandlingsmetode\/","name":"PUREX - genbehandlingsmetoden - Foreningen Atomkraft Ja Tak","isPartOf":{"@id":"https:\/\/www.atomkraft-jatak.dk\/newsite\/#website"},"datePublished":"2023-08-13T14:19:13+00:00","dateModified":"2024-09-14T20:41:02+00:00","description":"PUREX (Plutonium Uranium Extraction) er en kemisk proces, der anvendes til at udvinde plutonium og uran fra brugt br\u00e6ndsel i reaktorer","breadcrumb":{"@id":"https:\/\/www.atomkraft-jatak.dk\/newsite\/dokumenter\/purex-genbehandlingsmetode\/#breadcrumb"},"inLanguage":"da-DK","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.atomkraft-jatak.dk\/newsite\/dokumenter\/purex-genbehandlingsmetode\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.atomkraft-jatak.dk\/newsite\/dokumenter\/purex-genbehandlingsmetode\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.atomkraft-jatak.dk\/newsite\/"},{"@type":"ListItem","position":2,"name":"Docs","item":"https:\/\/www.atomkraft-jatak.dk\/newsite\/docs\/"},{"@type":"ListItem","position":3,"name":"PUREX &#8211; genbehandlingsmetoden"}]},{"@type":"WebSite","@id":"https:\/\/www.atomkraft-jatak.dk\/newsite\/#website","url":"https:\/\/www.atomkraft-jatak.dk\/newsite\/","name":"Foreningen Atomkraft Ja Tak","description":"- Brug hjernen, split kernen","publisher":{"@id":"https:\/\/www.atomkraft-jatak.dk\/newsite\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.atomkraft-jatak.dk\/newsite\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"da-DK"},{"@type":"Organization","@id":"https:\/\/www.atomkraft-jatak.dk\/newsite\/#organization","name":"Atomkraft Ja Tak","url":"https:\/\/www.atomkraft-jatak.dk\/newsite\/","logo":{"@type":"ImageObject","inLanguage":"da-DK","@id":"https:\/\/www.atomkraft-jatak.dk\/newsite\/#\/schema\/logo\/image\/","url":"https:\/\/www.atomkraft-jatak.dk\/newsite\/wp-content\/uploads\/2021\/02\/logo-med-hjemmeside.png","contentUrl":"https:\/\/www.atomkraft-jatak.dk\/newsite\/wp-content\/uploads\/2021\/02\/logo-med-hjemmeside.png","width":1452,"height":1470,"caption":"Atomkraft Ja Tak"},"image":{"@id":"https:\/\/www.atomkraft-jatak.dk\/newsite\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/atomkraftjatak\/"]}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"betterdocs-category-thumb":false,"1536x1536":false,"2048x2048":false,"woocommerce_thumbnail":false,"woocommerce_single":false,"woocommerce_gallery_thumbnail":false},"uagb_author_info":{"display_name":"Chris","author_link":"https:\/\/www.atomkraft-jatak.dk\/newsite\/author\/christian\/"},"uagb_comment_info":0,"uagb_excerpt":"Indledning PUREX (Plutonium Uranium Extraction) er en kemisk proces, der anvendes til at udvinde plutonium og uran fra brugt br\u00e6ndsel i nukleare reaktorer til produktionen af Mixed Oxide Fuel (MOX) br\u00e6ndsel som kan genbruges i en reaktor. De resterende fissionsprodukter og transuraner som reelt er affald, fylder nu fylder meget mindre og derfor kan deponeres&hellip;","_links":{"self":[{"href":"https:\/\/www.atomkraft-jatak.dk\/newsite\/wp-json\/wp\/v2\/docs\/29213"}],"collection":[{"href":"https:\/\/www.atomkraft-jatak.dk\/newsite\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/www.atomkraft-jatak.dk\/newsite\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/www.atomkraft-jatak.dk\/newsite\/wp-json\/wp\/v2\/users\/1297"}],"replies":[{"embeddable":true,"href":"https:\/\/www.atomkraft-jatak.dk\/newsite\/wp-json\/wp\/v2\/comments?post=29213"}],"version-history":[{"count":83,"href":"https:\/\/www.atomkraft-jatak.dk\/newsite\/wp-json\/wp\/v2\/docs\/29213\/revisions"}],"predecessor-version":[{"id":30467,"href":"https:\/\/www.atomkraft-jatak.dk\/newsite\/wp-json\/wp\/v2\/docs\/29213\/revisions\/30467"}],"wp:attachment":[{"href":"https:\/\/www.atomkraft-jatak.dk\/newsite\/wp-json\/wp\/v2\/media?parent=29213"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/www.atomkraft-jatak.dk\/newsite\/wp-json\/wp\/v2\/doc_category?post=29213"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/www.atomkraft-jatak.dk\/newsite\/wp-json\/wp\/v2\/doc_tag?post=29213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}